{"id":16646,"date":"2022-06-18T02:31:26","date_gmt":"2022-06-18T02:31:26","guid":{"rendered":"https:\/\/camlicatower.com\/home-page\/"},"modified":"2024-05-12T22:19:38","modified_gmt":"2024-05-12T22:19:38","slug":"home-page","status":"publish","type":"page","link":"https:\/\/camlicatower.com\/de\/","title":{"rendered":"Heim"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"16646\" class=\"elementor elementor-16646\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-76a27fb e-con-full e-flex e-con e-parent\" data-id=\"76a27fb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1014d1a elementor-hidden-tablet_extra elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-video\" data-id=\"1014d1a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;video_type&quot;:&quot;hosted&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;loop&quot;:&quot;yes&quot;,&quot;mute&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-hosted-video elementor-wrapper elementor-open-inline\">\n\t\t\t\t\t<video class=\"elementor-video\" src=\"http:\/\/camlicatower.com\/wp-content\/uploads\/2023\/08\/Camlica-Tower_1.mp4\" autoplay=\"\" loop=\"\" muted=\"muted\" controlsList=\"nodownload\"><\/video>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f518543 elementor-hidden-widescreen elementor-hidden-desktop elementor-hidden-laptop elementor-hidden-tablet_extra elementor-widget elementor-widget-video\" data-id=\"f518543\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;video_type&quot;:&quot;hosted&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;loop&quot;:&quot;yes&quot;,&quot;play_on_mobile&quot;:&quot;yes&quot;,&quot;mute&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-hosted-video elementor-wrapper elementor-open-inline\">\n\t\t\t\t\t<video class=\"elementor-video\" src=\"http:\/\/camlicatower.com\/wp-content\/uploads\/2023\/08\/Camlica-Tower_1.mp4\" autoplay=\"\" loop=\"\" muted=\"muted\" playsinline=\"\" controlsList=\"nodownload\"><\/video>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d7fe31c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d7fe31c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8e96e91\" data-id=\"8e96e91\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-33dad86 elementor-widget-widescreen__width-initial elementor-widget elementor-widget-heading\" data-id=\"33dad86\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">DIE CAMLICA<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d09feeb elementor-widget elementor-widget-heading\" data-id=\"d09feeb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">TURM<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e697245 elementor-widget elementor-widget-heading\" data-id=\"e697245\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Atemberaubende Ausblicke, unvergessliche Erlebnisse!\n<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e7d511f elementor-widget elementor-widget-button\" data-id=\"e7d511f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-xs\" href=\"http:\/\/camlicatower.com\/prices-times\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">BUCHEN SIE JETZT<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-f6df731 e-flex e-con-boxed e-con e-parent\" data-id=\"f6df731\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-6360949 e-con-full e-flex e-con e-child\" data-id=\"6360949\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5d48515 elementor-widget elementor-widget-loop-carousel\" data-id=\"5d48515\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;template_id&quot;:14447,&quot;slides_to_show&quot;:&quot;1&quot;,&quot;slides_to_show_laptop&quot;:&quot;1&quot;,&quot;slides_to_show_tablet_extra&quot;:&quot;1&quot;,&quot;slides_to_show_tablet&quot;:&quot;1&quot;,&quot;_skin&quot;:&quot;post&quot;,&quot;slides_to_show_widescreen&quot;:&quot;3&quot;,&quot;slides_to_show_mobile&quot;:&quot;1&quot;,&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;edit_handle_selector&quot;:&quot;.elementor-widget-container&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;offset_sides&quot;:&quot;none&quot;,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;image_spacing_custom_widescreen&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_tablet_extra&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"loop-carousel.post\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"swiper-container elementor-loop-container elementor-grid\" dir=\"ltr\">\n\t\t\t\t<div class=\"swiper-wrapper\" aria-live=\"off\">\n\t\t<style id=\"loop-14447\">.elementor-14447 .elementor-element.elementor-element-b734da3{--display:flex;--flex-direction:row;--container-widget-width:initial;--container-widget-height:100%;--container-widget-flex-grow:1;--container-widget-align-self:stretch;--flex-wrap-mobile:wrap;}.elementor-14447 .elementor-element.elementor-element-b734da3.e-con{--flex-grow:0;--flex-shrink:0;}.elementor-widget-posts .elementor-post__title, .elementor-widget-posts .elementor-post__title a{color:var( --e-global-color-secondary );font-family:var( --e-global-typography-primary-font-family ), Sans-serif;font-weight:var( --e-global-typography-primary-font-weight );}.elementor-widget-posts .elementor-post__meta-data{font-family:var( --e-global-typography-secondary-font-family ), Sans-serif;font-weight:var( --e-global-typography-secondary-font-weight );}.elementor-widget-posts .elementor-post__excerpt p{font-family:var( --e-global-typography-text-font-family ), Sans-serif;font-weight:var( --e-global-typography-text-font-weight );}.elementor-widget-posts .elementor-post__read-more{color:var( --e-global-color-accent );}.elementor-widget-posts a.elementor-post__read-more{font-family:var( --e-global-typography-accent-font-family ), Sans-serif;font-weight:var( --e-global-typography-accent-font-weight );}.elementor-widget-posts .elementor-post__card .elementor-post__badge{background-color:var( --e-global-color-accent );font-family:var( --e-global-typography-accent-font-family ), Sans-serif;font-weight:var( --e-global-typography-accent-font-weight );}.elementor-widget-posts .elementor-pagination{font-family:var( --e-global-typography-secondary-font-family ), Sans-serif;font-weight:var( --e-global-typography-secondary-font-weight );}.elementor-widget-posts .elementor-button{font-family:var( --e-global-typography-accent-font-family ), Sans-serif;font-weight:var( --e-global-typography-accent-font-weight );background-color:var( --e-global-color-accent );}.elementor-widget-posts .e-load-more-message{font-family:var( --e-global-typography-secondary-font-family ), Sans-serif;font-weight:var( --e-global-typography-secondary-font-weight );}.elementor-14447 .elementor-element.elementor-element-cab1bba{--grid-column-gap:30px;--grid-row-gap:35px;}.elementor-14447 .elementor-element.elementor-element-cab1bba .elementor-post__title, .elementor-14447 .elementor-element.elementor-element-cab1bba .elementor-post__title a{color:#FCFCFC;font-family:\"Open Sans\", Sans-serif;font-size:20px;font-weight:500;}.elementor-14447 .elementor-element.elementor-element-cab1bba .elementor-post__read-more{color:#F0B904;}.elementor-14447 .elementor-element.elementor-element-cab1bba > .elementor-widget-container{padding:12px 12px 24px 12px;background-color:#272727;}@media(min-width:768px){.elementor-14447 .elementor-element.elementor-element-b734da3{--width:144.077%;}}<\/style>\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"14447\" class=\"elementor elementor-14447 swiper-slide e-loop-item e-loop-item-20812 post-20812 post type-post status-publish format-standard has-post-thumbnail hentry category-unkategorisiert\" data-elementor-post-type=\"elementor_library\" role=\"group\" aria-roledescription=\"slide\" data-custom-edit-handle=\"1\">\n\t\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b734da3 e-con-full e-flex e-con e-parent\" data-id=\"b734da3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cab1bba elementor-grid-1 elementor-posts--thumbnail-none elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-widget elementor-widget-posts\" data-id=\"cab1bba\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;classic_columns&quot;:&quot;1&quot;,&quot;classic_columns_tablet&quot;:&quot;2&quot;,&quot;classic_columns_mobile&quot;:&quot;1&quot;,&quot;classic_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:35,&quot;sizes&quot;:[]},&quot;classic_row_gap_widescreen&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;classic_row_gap_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;classic_row_gap_tablet_extra&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;classic_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;classic_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.classic\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-classic elementor-grid\" dir=\"ltr\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-20812 post type-post status-publish format-standard has-post-thumbnail hentry category-unkategorisiert\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/camlicatower.com\/de\/camlica-hill-vs-camlica-tower-cual-es-la-diferencia\/\" >\n\t\t\t\tCamlica Hill vs Camlica Tower: \u00bfCual es la diferencia?\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/camlicatower.com\/de\/camlica-hill-vs-camlica-tower-cual-es-la-diferencia\/\" aria-label=\"Read more about Camlica Hill vs Camlica Tower: \u00bfCual es la diferencia?\" tabindex=\"-1\" >\n\t\t\tRead More \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"14447\" class=\"elementor elementor-14447 swiper-slide e-loop-item e-loop-item-20743 post-20743 post type-post status-publish format-standard has-post-thumbnail hentry category-unkategorisiert\" data-elementor-post-type=\"elementor_library\" role=\"group\" aria-roledescription=\"slide\" data-custom-edit-handle=\"1\">\n\t\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b734da3 e-con-full e-flex e-con e-parent\" data-id=\"b734da3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cab1bba elementor-grid-1 elementor-posts--thumbnail-none elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-widget elementor-widget-posts\" data-id=\"cab1bba\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;classic_columns&quot;:&quot;1&quot;,&quot;classic_columns_tablet&quot;:&quot;2&quot;,&quot;classic_columns_mobile&quot;:&quot;1&quot;,&quot;classic_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:35,&quot;sizes&quot;:[]},&quot;classic_row_gap_widescreen&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;classic_row_gap_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;classic_row_gap_tablet_extra&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;classic_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;classic_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.classic\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-classic elementor-grid\" dir=\"ltr\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-20812 post type-post status-publish format-standard has-post-thumbnail hentry category-unkategorisiert\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/camlicatower.com\/de\/camlica-hill-vs-camlica-tower-cual-es-la-diferencia\/\" >\n\t\t\t\tCamlica Hill vs Camlica Tower: \u00bfCual es la diferencia?\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/camlicatower.com\/de\/camlica-hill-vs-camlica-tower-cual-es-la-diferencia\/\" aria-label=\"Read more about Camlica Hill vs Camlica Tower: \u00bfCual es la diferencia?\" tabindex=\"-1\" >\n\t\t\tRead More \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"14447\" class=\"elementor elementor-14447 swiper-slide e-loop-item e-loop-item-20710 post-20710 post type-post status-publish format-standard has-post-thumbnail hentry category-unkategorisiert\" data-elementor-post-type=\"elementor_library\" role=\"group\" aria-roledescription=\"slide\" data-custom-edit-handle=\"1\">\n\t\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b734da3 e-con-full e-flex e-con e-parent\" data-id=\"b734da3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cab1bba elementor-grid-1 elementor-posts--thumbnail-none elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-widget elementor-widget-posts\" data-id=\"cab1bba\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;classic_columns&quot;:&quot;1&quot;,&quot;classic_columns_tablet&quot;:&quot;2&quot;,&quot;classic_columns_mobile&quot;:&quot;1&quot;,&quot;classic_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:35,&quot;sizes&quot;:[]},&quot;classic_row_gap_widescreen&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;classic_row_gap_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;classic_row_gap_tablet_extra&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;classic_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;classic_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.classic\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-classic elementor-grid\" dir=\"ltr\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-20812 post type-post status-publish format-standard has-post-thumbnail hentry category-unkategorisiert\">\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/camlicatower.com\/de\/camlica-hill-vs-camlica-tower-cual-es-la-diferencia\/\" >\n\t\t\t\tCamlica Hill vs Camlica Tower: \u00bfCual es la diferencia?\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/camlicatower.com\/de\/camlica-hill-vs-camlica-tower-cual-es-la-diferencia\/\" aria-label=\"Read more about Camlica Hill vs Camlica Tower: \u00bfCual es la diferencia?\" tabindex=\"-1\" >\n\t\t\tRead More \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-73ba15c e-con-full e-flex e-con e-child\" data-id=\"73ba15c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fb49636 elementor-view-default elementor-vertical-align-top elementor-widget elementor-widget-icon-box\" data-id=\"fb49636\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t            <div class=\"elementor-icon-box-wrapper \">\r\n                                                     \r\n                <div class=\"elementor-icon-box-content\">\r\n                                       <h3 class=\"elementor-icon-box-title \">\r\n                        <span   style=\"display:block;\">\r\n                       \r\n                         \u00d6ffnungszeiten                        <\/span>\r\n                    <\/h3>\r\n                                            <p class=\"elementor-icon-box-description\">\r\n                            10:00 \u2013 22:00                        <\/p>\r\n                                    <\/div>\r\n            <\/div>\r\n            \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0bbb8e3 e-con-full e-flex e-con e-child\" data-id=\"0bbb8e3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-070b14b elementor-view-default elementor-vertical-align-top elementor-widget elementor-widget-icon-box\" data-id=\"070b14b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t            <div class=\"elementor-icon-box-wrapper \">\r\n                                                     \r\n                <div class=\"elementor-icon-box-content\">\r\n                                       <h3 class=\"elementor-icon-box-title \">\r\n                        <a href=\"http:\/\/camlicatower.com\/seamless-visit-guide\/\"  style=\"display:block;\">\r\n                       \r\n                         Zugangskarte                        <\/a>\r\n                    <\/h3>\r\n                                            <p class=\"elementor-icon-box-description\">\r\n                            Komme zum Turm                        <\/p>\r\n                                    <\/div>\r\n            <\/div>\r\n            \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b7d1579 e-con-full e-flex e-con e-child\" data-id=\"b7d1579\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2c8b786 elementor-view-default elementor-vertical-align-top elementor-widget elementor-widget-icon-box\" data-id=\"2c8b786\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t            <div class=\"elementor-icon-box-wrapper \">\r\n                                                     \r\n                <div class=\"elementor-icon-box-content\">\r\n                                       <h3 class=\"elementor-icon-box-title \">\r\n                        <a href=\"http:\/\/camlicatower.com\/gallery\/\"  style=\"display:block;\">\r\n                       \r\n                         Ansichten vom Turm                        <\/a>\r\n                    <\/h3>\r\n                                            <p class=\"elementor-icon-box-description\">\r\n                            (Galerie)                        <\/p>\r\n                                    <\/div>\r\n            <\/div>\r\n            \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5ce83294 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5ce83294\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-55da6ec1\" data-id=\"55da6ec1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4f210ffb elementor-widget elementor-widget-heading\" data-id=\"4f210ffb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Bietet an<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7113c307 elementor-widget elementor-widget-st_list_service\" data-id=\"7113c307\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;order&quot;:&quot;DESC&quot;,&quot;type_form&quot;:&quot;single&quot;,&quot;item_row&quot;:&quot;3&quot;}\" data-widget_type=\"st_list_service.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t    <div class=\"st-list-service grid style_2\"     >\r\n        <div class=\"service-list-wrapper service-tour\"><div class=\"row\"><div class=\"col-12 col-sm-12 col-md-6 col-lg-6 col-xl-4\"><div class=\"services-item grid item-elementor\" itemscope itemtype=\"https:\/\/schema.org\/Event\">\r\n    <div class=\"item service-border st-border-radius\">\r\n        <div class=\"featured-image\">\r\n            <div class=\"st-tag-feature-sale\">\r\n                                                \r\n            <\/div>\r\n                            <a href=\"#\" class=\"login\" data-bs-toggle=\"modal\" data-bs-target=\"#st-login-form\">\r\n                    <div class=\"service-add-wishlist\" title=\"Add to wishlist\">\r\n                        <i class=\"st-border-radius field-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"23\" height=\"22\" viewBox=\"0 0 23 22\" fill=\"none\">\r\n        <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M0.75 7.68998C0.75 4.18927 3.57229 1.34998 7.06 1.34998C8.79674 1.34998 10.3646 2.05596 11.5003 3.19469C12.6385 2.05561 14.2122 1.34998 15.94 1.34998C19.4277 1.34998 22.25 4.18927 22.25 7.68998C22.25 11.4395 20.5107 14.4001 18.4342 16.5276C16.3683 18.6443 13.9235 19.9861 12.3657 20.5186C12.0914 20.6147 11.7773 20.65 11.5 20.65C11.2227 20.65 10.9086 20.6147 10.6343 20.5186C9.07655 19.9861 6.63169 18.6443 4.56577 16.5276C2.48932 14.4001 0.75 11.4395 0.75 7.68998Z\" fill=\"#232323\" fill-opacity=\"0.3\" stroke=\"white\" stroke-width=\"1.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\r\n        <\/svg><\/i>                        <div class=\"lds-dual-ring\"><\/div>\r\n                    <\/div>\r\n                <\/a>\r\n                        <a href=\"https:\/\/camlicatower.com\/de\/st_activity\/entry-ticket-with-free-turkish-tea\/\">\r\n                <img decoding=\"async\" itemprop=\"image\" src=\"https:\/\/camlicatower.com\/wp-content\/uploads\/2023\/08\/camlica-768x511.webp\"\r\n                     alt=\"Entdecken Sie den Camlica Tower mit einem kostenlosen t\u00fcrkischen Teeerlebnis (ohne Anstehen)\" class=\"image-feature st-hover-grow\"\/>\r\n            <\/a>\r\n                                <\/div>\r\n        <div class=\"content-item\">\r\n                            <div class=\"sub-title st-address d-flex align-items-center\" itemprop=\"location\" itemscope itemtype=\"https:\/\/schema.org\/Place\">\r\n                    <span itemprop=\"itinerary\" itemscope itemtype=\"https:\/\/schema.org\/ItemList\"> \r\n                        <span itemprop=\"streetAddress\"> <i class=\"stt-icon-location1\"><\/i> Istanbul<\/span>\r\n                    <\/span>\r\n                <\/div>\r\n                        <div class=\"event-date d-none\" itemprop=\"startDate\" content=\"2026-09-02 23:42:14\">2026-09-02 23:42:14<\/div>\r\n            <h3 class=\"title\" itemprop=\"name\">\r\n                <a href=\"https:\/\/camlicatower.com\/de\/st_activity\/entry-ticket-with-free-turkish-tea\/\"\r\n                   class=\"c-main\">Entdecken Sie den Camlica Tower mit einem kostenlosen t\u00fcrkischen Teeerlebnis (ohne Anstehen)<\/a>\r\n            <\/h3>\r\n            <div class=\"reviews\">\r\n                <i class=\"stt-icon-star1\"><\/i>\r\n                <span class=\"rate\" itemprop=\"ratingValue\">\r\n                    0                <\/span>\r\n                <span class=\"summary\">\r\n                    (No Review)\r\n                <\/span>\r\n            <\/div>\r\n            <div class=\"event-date d-none\" itemprop=\"startDate\" content=\"2026-09-02 23:42:14\">2026-09-02 23:42:14<\/div>\r\n            <div class=\"section-footer\">\r\n               \r\n                <div class=\"price-wrapper price-wrapper-tour d-flex align-items-end justify-content-between\">\r\n                    <span class=\"price-tour\">\r\n                        <span class=\"price d-flex justify-content-around flex-column\"><span class=\"sale-top\"><span class=\"text-lg lh1em item \"> \u20ac0,00<\/span><\/span><\/span>\r\n                    <\/span>\r\n                                                <span class=\"unit\"><i class=\"input-icon st-border-radius field-icon fa\"><svg height=\"16px\" width=\"16px\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\r\n     viewBox=\"0 0 24 24\" style=\"enable-background:new 0 0 24 24;\" xml:space=\"preserve\">\r\n\r\n<g fill=\"#5E6D77\">\r\n    <path d=\"M12,23.25C5.797,23.25,0.75,18.203,0.75,12C0.75,5.797,5.797,0.75,12,0.75c6.203,0,11.25,5.047,11.25,11.25\r\n        C23.25,18.203,18.203,23.25,12,23.25z M12,2.25c-5.376,0-9.75,4.374-9.75,9.75s4.374,9.75,9.75,9.75s9.75-4.374,9.75-9.75\r\n        S17.376,2.25,12,2.25z\"\/>\r\n    <path d=\"M15.75,16.5c-0.2,0-0.389-0.078-0.53-0.22l-2.25-2.25c-0.302,0.145-0.632,0.22-0.969,0.22c-1.241,0-2.25-1.009-2.25-2.25\r\n        c0-0.96,0.615-1.808,1.5-2.121V5.25c0-0.414,0.336-0.75,0.75-0.75s0.75,0.336,0.75,0.75v4.629c0.885,0.314,1.5,1.162,1.5,2.121\r\n        c0,0.338-0.075,0.668-0.22,0.969l2.25,2.25c0.292,0.292,0.292,0.768,0,1.061C16.139,16.422,15.95,16.5,15.75,16.5z M12,11.25\r\n        c-0.414,0-0.75,0.336-0.75,0.75s0.336,0.75,0.75,0.75s0.75-0.336,0.75-0.75S12.414,11.25,12,11.25z\"\/>\r\n<\/g>\r\n<\/svg><\/i>2 hours<\/span>\r\n                                            \r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div>\r\n\r\n<\/div><div class=\"col-12 col-sm-12 col-md-6 col-lg-6 col-xl-4\"><div class=\"services-item grid item-elementor\" itemscope itemtype=\"https:\/\/schema.org\/Event\">\r\n    <div class=\"item service-border st-border-radius\">\r\n        <div class=\"featured-image\">\r\n            <div class=\"st-tag-feature-sale\">\r\n                                                \r\n            <\/div>\r\n                            <a href=\"#\" class=\"login\" data-bs-toggle=\"modal\" data-bs-target=\"#st-login-form\">\r\n                    <div class=\"service-add-wishlist\" title=\"Add to wishlist\">\r\n                        <i class=\"st-border-radius field-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"23\" height=\"22\" viewBox=\"0 0 23 22\" fill=\"none\">\r\n        <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M0.75 7.68998C0.75 4.18927 3.57229 1.34998 7.06 1.34998C8.79674 1.34998 10.3646 2.05596 11.5003 3.19469C12.6385 2.05561 14.2122 1.34998 15.94 1.34998C19.4277 1.34998 22.25 4.18927 22.25 7.68998C22.25 11.4395 20.5107 14.4001 18.4342 16.5276C16.3683 18.6443 13.9235 19.9861 12.3657 20.5186C12.0914 20.6147 11.7773 20.65 11.5 20.65C11.2227 20.65 10.9086 20.6147 10.6343 20.5186C9.07655 19.9861 6.63169 18.6443 4.56577 16.5276C2.48932 14.4001 0.75 11.4395 0.75 7.68998Z\" fill=\"#232323\" fill-opacity=\"0.3\" stroke=\"white\" stroke-width=\"1.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\r\n        <\/svg><\/i>                        <div class=\"lds-dual-ring\"><\/div>\r\n                    <\/div>\r\n                <\/a>\r\n                        <a href=\"https:\/\/camlicatower.com\/de\/st_activity\/entry-ticket-with-hotel-transfer-premium-lunch-or-dinner-experience\/\">\r\n                <img decoding=\"async\" itemprop=\"image\" src=\"https:\/\/camlicatower.com\/wp-content\/uploads\/2023\/09\/camlica-tower-dinner-1-450x300.jpeg\"\r\n                     alt=\"Besuch des Camlica-Turms mit Hoteltransfer und Premium-Mittag- oder -Abendessen (ohne Anstehen)\" class=\"image-feature st-hover-grow\"\/>\r\n            <\/a>\r\n                                <\/div>\r\n        <div class=\"content-item\">\r\n                            <div class=\"sub-title st-address d-flex align-items-center\" itemprop=\"location\" itemscope itemtype=\"https:\/\/schema.org\/Place\">\r\n                    <span itemprop=\"itinerary\" itemscope itemtype=\"https:\/\/schema.org\/ItemList\"> \r\n                        <span itemprop=\"streetAddress\"> <i class=\"stt-icon-location1\"><\/i> Istanbul<\/span>\r\n                    <\/span>\r\n                <\/div>\r\n                        <div class=\"event-date d-none\" itemprop=\"startDate\" content=\"2026-09-02 23:42:14\">2026-09-02 23:42:14<\/div>\r\n            <h3 class=\"title\" itemprop=\"name\">\r\n                <a href=\"https:\/\/camlicatower.com\/de\/st_activity\/entry-ticket-with-hotel-transfer-premium-lunch-or-dinner-experience\/\"\r\n                   class=\"c-main\">Besuch des Camlica-Turms mit Hoteltransfer und Premium-Mittag- oder -Abendessen (ohne Anstehen)<\/a>\r\n            <\/h3>\r\n            <div class=\"reviews\">\r\n                <i class=\"stt-icon-star1\"><\/i>\r\n                <span class=\"rate\" itemprop=\"ratingValue\">\r\n                    0                <\/span>\r\n                <span class=\"summary\">\r\n                    (No Review)\r\n                <\/span>\r\n            <\/div>\r\n            <div class=\"event-date d-none\" itemprop=\"startDate\" content=\"2026-09-02 23:42:14\">2026-09-02 23:42:14<\/div>\r\n            <div class=\"section-footer\">\r\n               \r\n                <div class=\"price-wrapper price-wrapper-tour d-flex align-items-end justify-content-between\">\r\n                    <span class=\"price-tour\">\r\n                        <span class=\"price d-flex justify-content-around flex-column\"><span class=\"sale-top\"><span class=\"text-lg lh1em item \"> \u20ac0,00<\/span><\/span><\/span>\r\n                    <\/span>\r\n                                                <span class=\"unit\"><i class=\"input-icon st-border-radius field-icon fa\"><svg height=\"16px\" width=\"16px\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\r\n     viewBox=\"0 0 24 24\" style=\"enable-background:new 0 0 24 24;\" xml:space=\"preserve\">\r\n\r\n<g fill=\"#5E6D77\">\r\n    <path d=\"M12,23.25C5.797,23.25,0.75,18.203,0.75,12C0.75,5.797,5.797,0.75,12,0.75c6.203,0,11.25,5.047,11.25,11.25\r\n        C23.25,18.203,18.203,23.25,12,23.25z M12,2.25c-5.376,0-9.75,4.374-9.75,9.75s4.374,9.75,9.75,9.75s9.75-4.374,9.75-9.75\r\n        S17.376,2.25,12,2.25z\"\/>\r\n    <path d=\"M15.75,16.5c-0.2,0-0.389-0.078-0.53-0.22l-2.25-2.25c-0.302,0.145-0.632,0.22-0.969,0.22c-1.241,0-2.25-1.009-2.25-2.25\r\n        c0-0.96,0.615-1.808,1.5-2.121V5.25c0-0.414,0.336-0.75,0.75-0.75s0.75,0.336,0.75,0.75v4.629c0.885,0.314,1.5,1.162,1.5,2.121\r\n        c0,0.338-0.075,0.668-0.22,0.969l2.25,2.25c0.292,0.292,0.292,0.768,0,1.061C16.139,16.422,15.95,16.5,15.75,16.5z M12,11.25\r\n        c-0.414,0-0.75,0.336-0.75,0.75s0.336,0.75,0.75,0.75s0.75-0.336,0.75-0.75S12.414,11.25,12,11.25z\"\/>\r\n<\/g>\r\n<\/svg><\/i>5 hours<\/span>\r\n                                            \r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div>\r\n\r\n<\/div><div class=\"col-12 col-sm-12 col-md-6 col-lg-6 col-xl-4\"><div class=\"services-item grid item-elementor\" itemscope itemtype=\"https:\/\/schema.org\/Event\">\r\n    <div class=\"item service-border st-border-radius\">\r\n        <div class=\"featured-image\">\r\n            <div class=\"st-tag-feature-sale\">\r\n                                                \r\n            <\/div>\r\n                            <a href=\"#\" class=\"login\" data-bs-toggle=\"modal\" data-bs-target=\"#st-login-form\">\r\n                    <div class=\"service-add-wishlist\" title=\"Add to wishlist\">\r\n                        <i class=\"st-border-radius field-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"23\" height=\"22\" viewBox=\"0 0 23 22\" fill=\"none\">\r\n        <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M0.75 7.68998C0.75 4.18927 3.57229 1.34998 7.06 1.34998C8.79674 1.34998 10.3646 2.05596 11.5003 3.19469C12.6385 2.05561 14.2122 1.34998 15.94 1.34998C19.4277 1.34998 22.25 4.18927 22.25 7.68998C22.25 11.4395 20.5107 14.4001 18.4342 16.5276C16.3683 18.6443 13.9235 19.9861 12.3657 20.5186C12.0914 20.6147 11.7773 20.65 11.5 20.65C11.2227 20.65 10.9086 20.6147 10.6343 20.5186C9.07655 19.9861 6.63169 18.6443 4.56577 16.5276C2.48932 14.4001 0.75 11.4395 0.75 7.68998Z\" fill=\"#232323\" fill-opacity=\"0.3\" stroke=\"white\" stroke-width=\"1.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\r\n        <\/svg><\/i>                        <div class=\"lds-dual-ring\"><\/div>\r\n                    <\/div>\r\n                <\/a>\r\n                        <a href=\"https:\/\/camlicatower.com\/de\/st_activity\/entry-ticket-with-hotel-transfer-lunch-or-dinner-experience\/\">\r\n                <img decoding=\"async\" itemprop=\"image\" src=\"https:\/\/camlicatower.com\/wp-content\/uploads\/2023\/09\/camlica-tower-dinner-450x300.jpg\"\r\n                     alt=\"Entdecken Sie den Camlica Tower mit Hoteltransfer und Mittag- oder Abendessen (ohne Anstehen)\" class=\"image-feature st-hover-grow\"\/>\r\n            <\/a>\r\n                                <\/div>\r\n        <div class=\"content-item\">\r\n                            <div class=\"sub-title st-address d-flex align-items-center\" itemprop=\"location\" itemscope itemtype=\"https:\/\/schema.org\/Place\">\r\n                    <span itemprop=\"itinerary\" itemscope itemtype=\"https:\/\/schema.org\/ItemList\"> \r\n                        <span itemprop=\"streetAddress\"> <i class=\"stt-icon-location1\"><\/i> Istanbul<\/span>\r\n                    <\/span>\r\n                <\/div>\r\n                        <div class=\"event-date d-none\" itemprop=\"startDate\" content=\"2026-09-02 23:42:14\">2026-09-02 23:42:14<\/div>\r\n            <h3 class=\"title\" itemprop=\"name\">\r\n                <a href=\"https:\/\/camlicatower.com\/de\/st_activity\/entry-ticket-with-hotel-transfer-lunch-or-dinner-experience\/\"\r\n                   class=\"c-main\">Entdecken Sie den Camlica Tower mit Hoteltransfer und Mittag- oder Abendessen (ohne Anstehen)<\/a>\r\n            <\/h3>\r\n            <div class=\"reviews\">\r\n                <i class=\"stt-icon-star1\"><\/i>\r\n                <span class=\"rate\" itemprop=\"ratingValue\">\r\n                    0                <\/span>\r\n                <span class=\"summary\">\r\n                    (No Review)\r\n                <\/span>\r\n            <\/div>\r\n            <div class=\"event-date d-none\" itemprop=\"startDate\" content=\"2026-09-02 23:42:14\">2026-09-02 23:42:14<\/div>\r\n            <div class=\"section-footer\">\r\n               \r\n                <div class=\"price-wrapper price-wrapper-tour d-flex align-items-end justify-content-between\">\r\n                    <span class=\"price-tour\">\r\n                        <span class=\"price d-flex justify-content-around flex-column\"><span class=\"sale-top\"><span class=\"text-lg lh1em item \"> \u20ac0,00<\/span><\/span><\/span>\r\n                    <\/span>\r\n                                                <span class=\"unit\"><i class=\"input-icon st-border-radius field-icon fa\"><svg height=\"16px\" width=\"16px\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\r\n     viewBox=\"0 0 24 24\" style=\"enable-background:new 0 0 24 24;\" xml:space=\"preserve\">\r\n\r\n<g fill=\"#5E6D77\">\r\n    <path d=\"M12,23.25C5.797,23.25,0.75,18.203,0.75,12C0.75,5.797,5.797,0.75,12,0.75c6.203,0,11.25,5.047,11.25,11.25\r\n        C23.25,18.203,18.203,23.25,12,23.25z M12,2.25c-5.376,0-9.75,4.374-9.75,9.75s4.374,9.75,9.75,9.75s9.75-4.374,9.75-9.75\r\n        S17.376,2.25,12,2.25z\"\/>\r\n    <path d=\"M15.75,16.5c-0.2,0-0.389-0.078-0.53-0.22l-2.25-2.25c-0.302,0.145-0.632,0.22-0.969,0.22c-1.241,0-2.25-1.009-2.25-2.25\r\n        c0-0.96,0.615-1.808,1.5-2.121V5.25c0-0.414,0.336-0.75,0.75-0.75s0.75,0.336,0.75,0.75v4.629c0.885,0.314,1.5,1.162,1.5,2.121\r\n        c0,0.338-0.075,0.668-0.22,0.969l2.25,2.25c0.292,0.292,0.292,0.768,0,1.061C16.139,16.422,15.95,16.5,15.75,16.5z M12,11.25\r\n        c-0.414,0-0.75,0.336-0.75,0.75s0.336,0.75,0.75,0.75s0.75-0.336,0.75-0.75S12.414,11.25,12,11.25z\"\/>\r\n<\/g>\r\n<\/svg><\/i>5 hours<\/span>\r\n                                            \r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div>\r\n\r\n<\/div><div class=\"col-12 col-sm-12 col-md-6 col-lg-6 col-xl-4\"><div class=\"services-item grid item-elementor\" itemscope itemtype=\"https:\/\/schema.org\/Event\">\r\n    <div class=\"item service-border st-border-radius\">\r\n        <div class=\"featured-image\">\r\n            <div class=\"st-tag-feature-sale\">\r\n                                                \r\n            <\/div>\r\n                            <a href=\"#\" class=\"login\" data-bs-toggle=\"modal\" data-bs-target=\"#st-login-form\">\r\n                    <div class=\"service-add-wishlist\" title=\"Add to wishlist\">\r\n                        <i class=\"st-border-radius field-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"23\" height=\"22\" viewBox=\"0 0 23 22\" fill=\"none\">\r\n        <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M0.75 7.68998C0.75 4.18927 3.57229 1.34998 7.06 1.34998C8.79674 1.34998 10.3646 2.05596 11.5003 3.19469C12.6385 2.05561 14.2122 1.34998 15.94 1.34998C19.4277 1.34998 22.25 4.18927 22.25 7.68998C22.25 11.4395 20.5107 14.4001 18.4342 16.5276C16.3683 18.6443 13.9235 19.9861 12.3657 20.5186C12.0914 20.6147 11.7773 20.65 11.5 20.65C11.2227 20.65 10.9086 20.6147 10.6343 20.5186C9.07655 19.9861 6.63169 18.6443 4.56577 16.5276C2.48932 14.4001 0.75 11.4395 0.75 7.68998Z\" fill=\"#232323\" fill-opacity=\"0.3\" stroke=\"white\" stroke-width=\"1.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\r\n        <\/svg><\/i>                        <div class=\"lds-dual-ring\"><\/div>\r\n                    <\/div>\r\n                <\/a>\r\n                        <a href=\"https:\/\/camlicatower.com\/de\/st_activity\/entry-ticket-with-hotel-transfer-breakfast-experience\/\">\r\n                <img decoding=\"async\" itemprop=\"image\" src=\"https:\/\/camlicatower.com\/wp-content\/uploads\/2023\/09\/camlica-towerbreakfast-view-450x300.jpeg\"\r\n                     alt=\"camlica-tower\" class=\"image-feature st-hover-grow\"\/>\r\n            <\/a>\r\n                                <\/div>\r\n        <div class=\"content-item\">\r\n                            <div class=\"sub-title st-address d-flex align-items-center\" itemprop=\"location\" itemscope itemtype=\"https:\/\/schema.org\/Place\">\r\n                    <span itemprop=\"itinerary\" itemscope itemtype=\"https:\/\/schema.org\/ItemList\"> \r\n                        <span itemprop=\"streetAddress\"> <i class=\"stt-icon-location1\"><\/i> Istanbul<\/span>\r\n                    <\/span>\r\n                <\/div>\r\n                        <div class=\"event-date d-none\" itemprop=\"startDate\" content=\"2026-09-02 23:42:14\">2026-09-02 23:42:14<\/div>\r\n            <h3 class=\"title\" itemprop=\"name\">\r\n                <a href=\"https:\/\/camlicatower.com\/de\/st_activity\/entry-ticket-with-hotel-transfer-breakfast-experience\/\"\r\n                   class=\"c-main\">Entdeckungstour zum Camlica Tower mit Hoteltransfer und Fr\u00fchst\u00fcckserlebnis (ohne Anstehen)<\/a>\r\n            <\/h3>\r\n            <div class=\"reviews\">\r\n                <i class=\"stt-icon-star1\"><\/i>\r\n                <span class=\"rate\" itemprop=\"ratingValue\">\r\n                    0                <\/span>\r\n                <span class=\"summary\">\r\n                    (No Review)\r\n                <\/span>\r\n            <\/div>\r\n            <div class=\"event-date d-none\" itemprop=\"startDate\" content=\"2026-09-02 23:42:14\">2026-09-02 23:42:14<\/div>\r\n            <div class=\"section-footer\">\r\n               \r\n                <div class=\"price-wrapper price-wrapper-tour d-flex align-items-end justify-content-between\">\r\n                    <span class=\"price-tour\">\r\n                        <span class=\"price d-flex justify-content-around flex-column\"><span class=\"sale-top\"><span class=\"text-lg lh1em item \"> \u20ac0,00<\/span><\/span><\/span>\r\n                    <\/span>\r\n                                                <span class=\"unit\"><i class=\"input-icon st-border-radius field-icon fa\"><svg height=\"16px\" width=\"16px\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\r\n     viewBox=\"0 0 24 24\" style=\"enable-background:new 0 0 24 24;\" xml:space=\"preserve\">\r\n\r\n<g fill=\"#5E6D77\">\r\n    <path d=\"M12,23.25C5.797,23.25,0.75,18.203,0.75,12C0.75,5.797,5.797,0.75,12,0.75c6.203,0,11.25,5.047,11.25,11.25\r\n        C23.25,18.203,18.203,23.25,12,23.25z M12,2.25c-5.376,0-9.75,4.374-9.75,9.75s4.374,9.75,9.75,9.75s9.75-4.374,9.75-9.75\r\n        S17.376,2.25,12,2.25z\"\/>\r\n    <path d=\"M15.75,16.5c-0.2,0-0.389-0.078-0.53-0.22l-2.25-2.25c-0.302,0.145-0.632,0.22-0.969,0.22c-1.241,0-2.25-1.009-2.25-2.25\r\n        c0-0.96,0.615-1.808,1.5-2.121V5.25c0-0.414,0.336-0.75,0.75-0.75s0.75,0.336,0.75,0.75v4.629c0.885,0.314,1.5,1.162,1.5,2.121\r\n        c0,0.338-0.075,0.668-0.22,0.969l2.25,2.25c0.292,0.292,0.292,0.768,0,1.061C16.139,16.422,15.95,16.5,15.75,16.5z M12,11.25\r\n        c-0.414,0-0.75,0.336-0.75,0.75s0.336,0.75,0.75,0.75s0.75-0.336,0.75-0.75S12.414,11.25,12,11.25z\"\/>\r\n<\/g>\r\n<\/svg><\/i>4 hours<\/span>\r\n                                            \r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div>\r\n\r\n<\/div><div class=\"col-12 col-sm-12 col-md-6 col-lg-6 col-xl-4\"><div class=\"services-item grid item-elementor\" itemscope itemtype=\"https:\/\/schema.org\/Event\">\r\n    <div class=\"item service-border st-border-radius\">\r\n        <div class=\"featured-image\">\r\n            <div class=\"st-tag-feature-sale\">\r\n                                                \r\n            <\/div>\r\n                            <a href=\"#\" class=\"login\" data-bs-toggle=\"modal\" data-bs-target=\"#st-login-form\">\r\n                    <div class=\"service-add-wishlist\" title=\"Add to wishlist\">\r\n                        <i class=\"st-border-radius field-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"23\" height=\"22\" viewBox=\"0 0 23 22\" fill=\"none\">\r\n        <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M0.75 7.68998C0.75 4.18927 3.57229 1.34998 7.06 1.34998C8.79674 1.34998 10.3646 2.05596 11.5003 3.19469C12.6385 2.05561 14.2122 1.34998 15.94 1.34998C19.4277 1.34998 22.25 4.18927 22.25 7.68998C22.25 11.4395 20.5107 14.4001 18.4342 16.5276C16.3683 18.6443 13.9235 19.9861 12.3657 20.5186C12.0914 20.6147 11.7773 20.65 11.5 20.65C11.2227 20.65 10.9086 20.6147 10.6343 20.5186C9.07655 19.9861 6.63169 18.6443 4.56577 16.5276C2.48932 14.4001 0.75 11.4395 0.75 7.68998Z\" fill=\"#232323\" fill-opacity=\"0.3\" stroke=\"white\" stroke-width=\"1.5\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\r\n        <\/svg><\/i>                        <div class=\"lds-dual-ring\"><\/div>\r\n                    <\/div>\r\n                <\/a>\r\n                        <a href=\"https:\/\/camlicatower.com\/de\/st_activity\/camlica-tower-entry-ticket-with-private-hotel-transfer-turkish-coffee-experience\/\">\r\n                <img decoding=\"async\" itemprop=\"image\" src=\"https:\/\/camlicatower.com\/wp-content\/uploads\/2022\/05\/camlica-enty-ticket-450x300.webp\"\r\n                     alt=\"Entdecken Sie den Camlica Tower mit Hoteltransfer und t\u00fcrkischem Kaffeeerlebnis (ohne Anstehen)\" class=\"image-feature st-hover-grow\"\/>\r\n            <\/a>\r\n                                <\/div>\r\n        <div class=\"content-item\">\r\n                            <div class=\"sub-title st-address d-flex align-items-center\" itemprop=\"location\" itemscope itemtype=\"https:\/\/schema.org\/Place\">\r\n                    <span itemprop=\"itinerary\" itemscope itemtype=\"https:\/\/schema.org\/ItemList\"> \r\n                        <span itemprop=\"streetAddress\"> <i class=\"stt-icon-location1\"><\/i> Istanbul<\/span>\r\n                    <\/span>\r\n                <\/div>\r\n                        <div class=\"event-date d-none\" itemprop=\"startDate\" content=\"2026-09-02 23:42:14\">2026-09-02 23:42:14<\/div>\r\n            <h3 class=\"title\" itemprop=\"name\">\r\n                <a href=\"https:\/\/camlicatower.com\/de\/st_activity\/camlica-tower-entry-ticket-with-private-hotel-transfer-turkish-coffee-experience\/\"\r\n                   class=\"c-main\">Entdecken Sie den Camlica Tower mit Hoteltransfer und t\u00fcrkischem Kaffeeerlebnis (ohne Anstehen)<\/a>\r\n            <\/h3>\r\n            <div class=\"reviews\">\r\n                <i class=\"stt-icon-star1\"><\/i>\r\n                <span class=\"rate\" itemprop=\"ratingValue\">\r\n                    0                <\/span>\r\n                <span class=\"summary\">\r\n                    (No Review)\r\n                <\/span>\r\n            <\/div>\r\n            <div class=\"event-date d-none\" itemprop=\"startDate\" content=\"2026-09-02 23:42:14\">2026-09-02 23:42:14<\/div>\r\n            <div class=\"section-footer\">\r\n               \r\n                <div class=\"price-wrapper price-wrapper-tour d-flex align-items-end justify-content-between\">\r\n                    <span class=\"price-tour\">\r\n                        <span class=\"price d-flex justify-content-around flex-column\"><span class=\"sale-top\"><span class=\"text-lg lh1em item \"> \u20ac0,00<\/span><\/span><\/span>\r\n                    <\/span>\r\n                                                <span class=\"unit\"><i class=\"input-icon st-border-radius field-icon fa\"><svg height=\"16px\" width=\"16px\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\"\r\n     viewBox=\"0 0 24 24\" style=\"enable-background:new 0 0 24 24;\" xml:space=\"preserve\">\r\n\r\n<g fill=\"#5E6D77\">\r\n    <path d=\"M12,23.25C5.797,23.25,0.75,18.203,0.75,12C0.75,5.797,5.797,0.75,12,0.75c6.203,0,11.25,5.047,11.25,11.25\r\n        C23.25,18.203,18.203,23.25,12,23.25z M12,2.25c-5.376,0-9.75,4.374-9.75,9.75s4.374,9.75,9.75,9.75s9.75-4.374,9.75-9.75\r\n        S17.376,2.25,12,2.25z\"\/>\r\n    <path d=\"M15.75,16.5c-0.2,0-0.389-0.078-0.53-0.22l-2.25-2.25c-0.302,0.145-0.632,0.22-0.969,0.22c-1.241,0-2.25-1.009-2.25-2.25\r\n        c0-0.96,0.615-1.808,1.5-2.121V5.25c0-0.414,0.336-0.75,0.75-0.75s0.75,0.336,0.75,0.75v4.629c0.885,0.314,1.5,1.162,1.5,2.121\r\n        c0,0.338-0.075,0.668-0.22,0.969l2.25,2.25c0.292,0.292,0.292,0.768,0,1.061C16.139,16.422,15.95,16.5,15.75,16.5z M12,11.25\r\n        c-0.414,0-0.75,0.336-0.75,0.75s0.336,0.75,0.75,0.75s0.75-0.336,0.75-0.75S12.414,11.25,12,11.25z\"\/>\r\n<\/g>\r\n<\/svg><\/i>4 hours<\/span>\r\n                                            \r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/div>\r\n\r\n<\/div><\/div><\/div>    <\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-75f0f33 e-flex e-con-boxed e-con e-parent\" data-id=\"75f0f33\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-eb78b73 e-con-full e-flex e-con e-child\" data-id=\"eb78b73\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-efc8b67 elementor-widget elementor-widget-image\" data-id=\"efc8b67\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/camlicatower.com\/wp-content\/uploads\/elementor\/thumbs\/kule-entry-1-q9satmtqz1uaca1mjbrlbm3r1lh18iyvzi8g1wlkkw.jpg\" title=\"kule entry\" alt=\"kule entry\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b079a07 e-con-full e-flex e-con e-child\" data-id=\"b079a07\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-94d2f70 elementor-widget elementor-widget-heading\" data-id=\"94d2f70\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Entdecken Sie Istanbuls Juwel: 6 Gr\u00fcnde, den Camlica Tower zu besuchen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bcb2bfc elementor-widget elementor-widget-text-editor\" data-id=\"bcb2bfc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul>\n<li><strong>Einzigartiger Panoramablick:<\/strong> Der Camlica Tower bietet einen atemberaubenden 360-Grad-Blick auf Istanbul.<\/li>\n<li><strong>Ausgezeichnetes kulinarisches Erlebnis:<\/strong> Genie\u00dfen Sie k\u00f6stliche Mahlzeiten gepaart mit atemberaubenden Ausblicken auf die Stadt in den Restaurants des Turms.<\/li>\n<li><strong>Historischer und kultureller Reichtum:<\/strong> Der Camlica-Turm ist ein Zeugnis der geschichtstr\u00e4chtigen Vergangenheit und lebendigen Kultur Istanbuls.<\/li>\n<li><strong>Historischer und kultureller Reichtum:<\/strong> Der Camlica-Turm ist ein Zeugnis der geschichtstr\u00e4chtigen Vergangenheit und lebendigen Kultur Istanbuls.<\/li>\n<li><strong>Aufregendes Seyyah 360-Erlebnis:<\/strong> Tauchen Sie von Camlica aus in eine virtuelle Panoramatour zu den Wundern Istanbuls ein.<\/li>\n<li><strong>Einzigartige Mission Moon:<\/strong> Erleben Sie ein Mondabenteuer mit Camlicas interaktiver Mission Moon-Ausstellung.<\/li>\n<\/ul>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fad5f2e e-flex e-con-boxed e-con e-parent\" data-id=\"fad5f2e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-15534d9 elementor-widget elementor-widget-heading\" data-id=\"15534d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Nicht Verpassen<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-03418e2 e-flex e-con-boxed e-con e-parent\" data-id=\"03418e2\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-b88b2f7 e-con-full e-flex e-con e-child\" data-id=\"b88b2f7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3a7bc88 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"3a7bc88\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"http:\/\/camlicatower.com\/activities\/\" tabindex=\"-1\"><img decoding=\"async\" src=\"https:\/\/camlicatower.com\/wp-content\/uploads\/elementor\/thumbs\/seyyah-360-qaojgrmptc7z2re6jznfn4locvaw4zomj87i8xdggw.png\" title=\"seyyah 360\" alt=\"seyyah 360\" loading=\"lazy\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"http:\/\/camlicatower.com\/activities\/\">Seyyah 360<\/a><\/h3><p class=\"elementor-image-box-description\">Tauchen Sie ein in das Herz von Istanbul mit dem mehrdimensionalen Filmerlebnis von Seyyah 360 im Camlica Tower.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8096879 elementor-widget elementor-widget-spacer\" data-id=\"8096879\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-67ff4db e-con-full e-flex e-con e-child\" data-id=\"67ff4db\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ced5512 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"ced5512\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"http:\/\/camlicatower.com\/restaurant-cafe-gift-shop\/\" tabindex=\"-1\"><img fetchpriority=\"high\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/camlicatower.com\/wp-content\/uploads\/2023\/07\/seyyah-4.webp\" class=\"attachment-full size-full wp-image-14616\" alt=\"\" srcset=\"https:\/\/camlicatower.com\/wp-content\/uploads\/2023\/07\/seyyah-4.webp 600w, https:\/\/camlicatower.com\/wp-content\/uploads\/2023\/07\/seyyah-4-768x512.webp 768w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"http:\/\/camlicatower.com\/restaurant-cafe-gift-shop\/\">Restaurant &amp; Caf\u00e9<\/a><\/h3><p class=\"elementor-image-box-description\">Genie\u00dfen Sie die Aromen Istanbuls im 360 Kule Caf\u00e9 &amp; Restaurant, das exquisite Speisen mit Aussicht bietet.<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1ef3405 elementor-widget-laptop__width-initial elementor-widget elementor-widget-spacer\" data-id=\"1ef3405\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f19f4b5 e-con-full e-flex e-con e-child\" data-id=\"f19f4b5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-836a697 elementor-position-top elementor-widget elementor-widget-image-box\" data-id=\"836a697\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><a href=\"http:\/\/camlicatower.com\/activities\/\" tabindex=\"-1\"><img decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/camlicatower.com\/wp-content\/uploads\/2023\/08\/mission-moon-1-.webp\" class=\"attachment-full size-full wp-image-14804\" alt=\"\" srcset=\"https:\/\/camlicatower.com\/wp-content\/uploads\/2023\/08\/mission-moon-1-.webp 600w, https:\/\/camlicatower.com\/wp-content\/uploads\/2023\/08\/mission-moon-1--768x512.webp 768w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\"><a href=\"http:\/\/camlicatower.com\/activities\/\">Mission Mond<\/a><\/h3><p class=\"elementor-image-box-description\">Mission Moon bietet eine aufregende Weltraumreise zum Mond und stellt sich eine unterhaltsame Zukunft vor.\u200b<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bf096ff e-flex e-con-boxed e-con e-parent\" data-id=\"bf096ff\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-25720d8 e-con-full e-flex e-con e-child\" data-id=\"25720d8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a360d5e elementor-widget elementor-widget-image\" data-id=\"a360d5e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/camlicatower.com\/wp-content\/uploads\/elementor\/thumbs\/sunset-camlica-tower-qam5abjusqsa0i6thrlf36dxtrahl3m4f4pgvecxo0.webp\" title=\"sunset camlica tower\" alt=\"sunset camlica tower\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-11b7dd1 e-con-full e-flex e-con e-child\" data-id=\"11b7dd1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4d42c99 elementor-widget elementor-widget-heading\" data-id=\"4d42c99\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Sky High: Die Reise zum Camlica Tower<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-42a3ac5 elementor-widget elementor-widget-text-editor\" data-id=\"42a3ac5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><span style=\"font-weight: 400;\">Steigen Sie am Camlica-Turm auf die Spitze von Istanbul. Entdecken Sie unvergleichliche Ausblicke, historische Wunder und den Herzschlag der Stadt von unserem himmelhohen Aussichtspunkt aus. Erleben Sie die Pracht Istanbuls auf einer unvergleichlichen Reise.<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4238a43 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"4238a43\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"http:\/\/camlicatower.com\/explore\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Entdecken Sie den Camlica-Turm<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a2a7ebd e-flex e-con-boxed e-con e-parent\" data-id=\"a2a7ebd\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c82301a elementor-widget elementor-widget-heading\" data-id=\"c82301a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"http:\/\/camlicatower.com\/gallery\/\">Ansichten vom Turm<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8601547 e-flex e-con-boxed e-con e-parent\" data-id=\"8601547\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9f03920 elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"9f03920\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;arrows&quot;,&quot;slides_to_show_mobile&quot;:&quot;1&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Bild Karussell\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 von 6\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"9f03920\" data-elementor-lightbox-title=\"seyyah-1\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTQ2MTgsInVybCI6Imh0dHBzOlwvXC9jYW1saWNhdG93ZXIuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDIzXC8wN1wvc2V5eWFoLTEud2VicCIsInNsaWRlc2hvdyI6IjlmMDM5MjAifQ%3D%3D\" href=\"http:\/\/camlicatower.com\/gallery\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/camlicatower.com\/wp-content\/uploads\/elementor\/thumbs\/seyyah-1-qa6yq31y055wfz83bijunvsg3z7uv3msee77s84nm0.webp\" alt=\"seyyah-1\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 von 6\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"9f03920\" data-elementor-lightbox-title=\"seyyah 5\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTQ2MTcsInVybCI6Imh0dHBzOlwvXC9jYW1saWNhdG93ZXIuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDIzXC8wN1wvc2V5eWFoLTUtLndlYnAiLCJzbGlkZXNob3ciOiI5ZjAzOTIwIn0%3D\" href=\"http:\/\/camlicatower.com\/gallery\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/camlicatower.com\/wp-content\/uploads\/elementor\/thumbs\/seyyah-5--qa6ypycr1yzgtxex2yiptez551v0sm44pqxsdubmh4.webp\" alt=\"seyyah 5\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 von 6\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"9f03920\" data-elementor-lightbox-title=\"seyyah 4\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTQ2MTYsInVybCI6Imh0dHBzOlwvXC9jYW1saWNhdG93ZXIuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDIzXC8wN1wvc2V5eWFoLTQud2VicCIsInNsaWRlc2hvdyI6IjlmMDM5MjAifQ%3D%3D\" href=\"http:\/\/camlicatower.com\/gallery\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/camlicatower.com\/wp-content\/uploads\/elementor\/thumbs\/seyyah-4-qa6ypsppwyrqw9n3zw2yegedkqmtifhqoz0vi6jzig.webp\" alt=\"seyyah 4\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 von 6\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"9f03920\" data-elementor-lightbox-title=\"muze-2-mission-moon\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTQ1NjYsInVybCI6Imh0dHBzOlwvXC9jYW1saWNhdG93ZXIuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDIzXC8wN1wvbXV6ZS0yLW1pc3Npb24tbW9vbi53ZWJwIiwic2xpZGVzaG93IjoiOWYwMzkyMCJ9\" href=\"http:\/\/camlicatower.com\/gallery\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/camlicatower.com\/wp-content\/uploads\/elementor\/thumbs\/muze-2-mission-moon-qa4v1de5018jsf0sq8r7dydhfizb8vpmsbgbxy36a0.webp\" alt=\"muze-2-mission-moon\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 von 6\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"9f03920\" data-elementor-lightbox-title=\"seyyah 2\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTQ2MTQsInVybCI6Imh0dHBzOlwvXC9jYW1saWNhdG93ZXIuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDIzXC8wN1wvc2V5eWFoLTItLndlYnAiLCJzbGlkZXNob3ciOiI5ZjAzOTIwIn0%3D\" href=\"http:\/\/camlicatower.com\/gallery\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/camlicatower.com\/wp-content\/uploads\/elementor\/thumbs\/seyyah-2--qa6ypidhtsdlck24o9m2510b1i1s5rcozjuj84zbew.webp\" alt=\"seyyah 2\" \/><\/figure><\/a><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 von 6\"><a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"9f03920\" data-elementor-lightbox-title=\"camlica-tower-gift-shop\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTQ1MzQsInVybCI6Imh0dHBzOlwvXC9jYW1saWNhdG93ZXIuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDIyXC8wNVwvY2FtbGljYS10b3dlci0yLndlYnAiLCJzbGlkZXNob3ciOiI5ZjAzOTIwIn0%3D\" href=\"http:\/\/camlicatower.com\/gallery\/\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/camlicatower.com\/wp-content\/uploads\/elementor\/thumbs\/camlica-tower-2-qa4io0h0uxkovnxib8frhu84y83j7mo1vzv958fceg.webp\" alt=\"camlica-tower-gift-shop\" \/><\/figure><\/a><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3d006909 e-flex e-con-boxed e-con e-parent\" data-id=\"3d006909\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-798c0d1b elementor-widget elementor-widget-heading\" data-id=\"798c0d1b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">H\u00e4ufig gestellte Fragen zum Camlica-Turm\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-48cdf2fe e-flex e-con-boxed e-con e-child\" data-id=\"48cdf2fe\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6a816b71 elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-widget-widescreen__width-initial elementor-widget elementor-widget-toggle\" data-id=\"6a816b71\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h4 id=\"elementor-tab-title-1781\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1781\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"b159ff04-3740-4ac3-96cc-b414ded50b3a\" data-name=\"Layer 1\" width=\"16\" height=\"16\" viewBox=\"0 0 16 16\"><polygon points=\"8.39 7.64 8.39 0 7.61 0 7.61 7.64 0 7.64 0 8.4 7.61 8.4 7.61 16 8.39 16 8.39 8.4 16 8.4 16 7.64 8.39 7.64\"><\/polygon><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"adf49d60-5815-4ece-8d49-00a021de5c06\" data-name=\"Layer 1\" width=\"16\" height=\"16\" viewBox=\"0 0 16 16\"><rect width=\"16\" height=\"16\" style=\"opacity:0\"><\/rect><rect y=\"7.64\" width=\"16\" height=\"0.76\"><\/rect><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Was kostet der Eintritt zum Camlica-Turm?<\/a>\n\t\t\t\t\t<\/h4>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1781\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1781\"><p><span style=\"font-weight: 400;\">Finden Sie es heraus: <a href=\"http:\/\/camlicatower.com\/prices-times\/\">Bitte \u00fcberpr\u00fcfen<\/a><\/span><\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h4 id=\"elementor-tab-title-1782\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-1782\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"b159ff04-3740-4ac3-96cc-b414ded50b3a\" data-name=\"Layer 1\" width=\"16\" height=\"16\" viewBox=\"0 0 16 16\"><polygon points=\"8.39 7.64 8.39 0 7.61 0 7.61 7.64 0 7.64 0 8.4 7.61 8.4 7.61 16 8.39 16 8.39 8.4 16 8.4 16 7.64 8.39 7.64\"><\/polygon><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"adf49d60-5815-4ece-8d49-00a021de5c06\" data-name=\"Layer 1\" width=\"16\" height=\"16\" viewBox=\"0 0 16 16\"><rect width=\"16\" height=\"16\" style=\"opacity:0\"><\/rect><rect y=\"7.64\" width=\"16\" height=\"0.76\"><\/rect><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Ist es m\u00f6glich, Tickets f\u00fcr den Camlica Tower Istanbul online zu kaufen?<\/a>\n\t\t\t\t\t<\/h4>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1782\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-1782\"><p><span style=\"font-weight: 400;\">Absolut, das k\u00f6nnen Sie! Wir empfehlen Ihnen, Ihre Tickets online zu kaufen, um Ihren Besuch zu optimieren.&nbsp;<\/span><\/p>\n<p><a href=\"http:\/\/camlicatower.com\/prices-times\/\" target=\"_blank\">Bitte \u00fcberpr\u00fcfen<\/a><\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h4 id=\"elementor-tab-title-1783\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-1783\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"b159ff04-3740-4ac3-96cc-b414ded50b3a\" data-name=\"Layer 1\" width=\"16\" height=\"16\" viewBox=\"0 0 16 16\"><polygon points=\"8.39 7.64 8.39 0 7.61 0 7.61 7.64 0 7.64 0 8.4 7.61 8.4 7.61 16 8.39 16 8.39 8.4 16 8.4 16 7.64 8.39 7.64\"><\/polygon><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"adf49d60-5815-4ece-8d49-00a021de5c06\" data-name=\"Layer 1\" width=\"16\" height=\"16\" viewBox=\"0 0 16 16\"><rect width=\"16\" height=\"16\" style=\"opacity:0\"><\/rect><rect y=\"7.64\" width=\"16\" height=\"0.76\"><\/rect><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Wann ist der Camlica-Turm f\u00fcr die \u00d6ffentlichkeit zug\u00e4nglich?<\/a>\n\t\t\t\t\t<\/h4>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1783\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-1783\"><p><span style=\"font-weight: 400;\">Besucher k\u00f6nnen den Camlica-Turm bereits von 10:00 bis 22:00 Uhr erkunden.<\/span><\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h4 id=\"elementor-tab-title-1784\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-1784\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"b159ff04-3740-4ac3-96cc-b414ded50b3a\" data-name=\"Layer 1\" width=\"16\" height=\"16\" viewBox=\"0 0 16 16\"><polygon points=\"8.39 7.64 8.39 0 7.61 0 7.61 7.64 0 7.64 0 8.4 7.61 8.4 7.61 16 8.39 16 8.39 8.4 16 8.4 16 7.64 8.39 7.64\"><\/polygon><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"adf49d60-5815-4ece-8d49-00a021de5c06\" data-name=\"Layer 1\" width=\"16\" height=\"16\" viewBox=\"0 0 16 16\"><rect width=\"16\" height=\"16\" style=\"opacity:0\"><\/rect><rect y=\"7.64\" width=\"16\" height=\"0.76\"><\/rect><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Wie buche ich einen Besuch im Camlica-Turm?<\/a>\n\t\t\t\t\t<\/h4>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1784\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-1784\"><p><span style=\"font-weight: 400;\">Sichern Sie sich jetzt Ihren Platz: <a href=\"http:\/\/camlicatower.com\/prices-times\/\">Bitte ankreuzen<\/a><\/span><\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h4 id=\"elementor-tab-title-1785\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-1785\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"b159ff04-3740-4ac3-96cc-b414ded50b3a\" data-name=\"Layer 1\" width=\"16\" height=\"16\" viewBox=\"0 0 16 16\"><polygon points=\"8.39 7.64 8.39 0 7.61 0 7.61 7.64 0 7.64 0 8.4 7.61 8.4 7.61 16 8.39 16 8.39 8.4 16 8.4 16 7.64 8.39 7.64\"><\/polygon><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"adf49d60-5815-4ece-8d49-00a021de5c06\" data-name=\"Layer 1\" width=\"16\" height=\"16\" viewBox=\"0 0 16 16\"><rect width=\"16\" height=\"16\" style=\"opacity:0\"><\/rect><rect y=\"7.64\" width=\"16\" height=\"0.76\"><\/rect><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Welche M\u00f6glichkeiten habe ich, den Camlica-Turm zu erreichen?<\/a>\n\t\t\t\t\t<\/h4>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1785\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-1785\"><p><span style=\"font-weight: 400;\">Der Camlica-Turm ist bequem mit \u00f6ffentlichen Verkehrsmitteln und Taxis zu erreichen und kann von der europ\u00e4ischen Seite aus mit einem einfachen Taxi erreicht werden, das etwa 40 Euro kostet. Pendler mit \u00f6ffentlichen Verkehrsmitteln k\u00f6nnen die Marmaray-Linie zum Bahnhof \u00dcsk\u00fcdar nehmen und anschlie\u00dfend den Bus Nr. 15 von \u00dcsk\u00fcdar nach Camlica nehmen. Dar\u00fcber hinaus k\u00f6nnen Sie mit Taxis direkt zum Turm fahren. Wenn Sie mit dem Auto anreisen, stehen Ihnen am Camlica Tower Parkpl\u00e4tze zur Verf\u00fcgung.<\/span><\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h4 id=\"elementor-tab-title-1786\" class=\"elementor-tab-title\" data-tab=\"6\" role=\"button\" aria-controls=\"elementor-tab-content-1786\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"b159ff04-3740-4ac3-96cc-b414ded50b3a\" data-name=\"Layer 1\" width=\"16\" height=\"16\" viewBox=\"0 0 16 16\"><polygon points=\"8.39 7.64 8.39 0 7.61 0 7.61 7.64 0 7.64 0 8.4 7.61 8.4 7.61 16 8.39 16 8.39 8.4 16 8.4 16 7.64 8.39 7.64\"><\/polygon><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"adf49d60-5815-4ece-8d49-00a021de5c06\" data-name=\"Layer 1\" width=\"16\" height=\"16\" viewBox=\"0 0 16 16\"><rect width=\"16\" height=\"16\" style=\"opacity:0\"><\/rect><rect y=\"7.64\" width=\"16\" height=\"0.76\"><\/rect><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Wie zug\u00e4nglich ist der Camlica-Turm?<\/a>\n\t\t\t\t\t<\/h4>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1786\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"6\" role=\"region\" aria-labelledby=\"elementor-tab-title-1786\"><p><span style=\"font-weight: 400;\">Wir sind stolz darauf, verk\u00fcnden zu k\u00f6nnen, dass der Camlica Tower vollst\u00e4ndig f\u00fcr den Empfang von Rollstuhlfahrern ausgestattet ist. Wir sind bestrebt, die beeindruckenden Aussichten und Einrichtungen, die der Turm bietet, allen Besuchern zug\u00e4nglich zu machen.<\/span><\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h4 id=\"elementor-tab-title-1787\" class=\"elementor-tab-title\" data-tab=\"7\" role=\"button\" aria-controls=\"elementor-tab-content-1787\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"b159ff04-3740-4ac3-96cc-b414ded50b3a\" data-name=\"Layer 1\" width=\"16\" height=\"16\" viewBox=\"0 0 16 16\"><polygon points=\"8.39 7.64 8.39 0 7.61 0 7.61 7.64 0 7.64 0 8.4 7.61 8.4 7.61 16 8.39 16 8.39 8.4 16 8.4 16 7.64 8.39 7.64\"><\/polygon><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"adf49d60-5815-4ece-8d49-00a021de5c06\" data-name=\"Layer 1\" width=\"16\" height=\"16\" viewBox=\"0 0 16 16\"><rect width=\"16\" height=\"16\" style=\"opacity:0\"><\/rect><rect y=\"7.64\" width=\"16\" height=\"0.76\"><\/rect><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Was muss ich nach dem Kauf meines Tickets tun?<\/a>\n\t\t\t\t\t<\/h4>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1787\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"7\" role=\"region\" aria-labelledby=\"elementor-tab-title-1787\"><p><span style=\"font-weight: 400;\">Sobald Sie Ihr Ticket in der Hand haben, k\u00f6nnen Sie unsere weitl\u00e4ufigen G\u00e4rten genie\u00dfen oder die Inneneinrichtungen im Turm wie unsere Cafeteria und verschiedene Aktivit\u00e4tsbereiche erkunden.<\/span><\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h4 id=\"elementor-tab-title-1788\" class=\"elementor-tab-title\" data-tab=\"8\" role=\"button\" aria-controls=\"elementor-tab-content-1788\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"b159ff04-3740-4ac3-96cc-b414ded50b3a\" data-name=\"Layer 1\" width=\"16\" height=\"16\" viewBox=\"0 0 16 16\"><polygon points=\"8.39 7.64 8.39 0 7.61 0 7.61 7.64 0 7.64 0 8.4 7.61 8.4 7.61 16 8.39 16 8.39 8.4 16 8.4 16 7.64 8.39 7.64\"><\/polygon><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"adf49d60-5815-4ece-8d49-00a021de5c06\" data-name=\"Layer 1\" width=\"16\" height=\"16\" viewBox=\"0 0 16 16\"><rect width=\"16\" height=\"16\" style=\"opacity:0\"><\/rect><rect y=\"7.64\" width=\"16\" height=\"0.76\"><\/rect><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Wie lange kann ich auf der Aussichtsplattform am Turm bleiben?<\/a>\n\t\t\t\t\t<\/h4>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1788\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"8\" role=\"region\" aria-labelledby=\"elementor-tab-title-1788\"><p><span style=\"font-weight: 400;\">Damit alle unsere Besucher die Aussicht ausreichend genie\u00dfen k\u00f6nnen, erlauben wir auf unseren Aussichtsplattformen eine Besuchsdauer von bis zu eineinhalb Stunden.<\/span><\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h4 id=\"elementor-tab-title-1789\" class=\"elementor-tab-title\" data-tab=\"9\" role=\"button\" aria-controls=\"elementor-tab-content-1789\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"b159ff04-3740-4ac3-96cc-b414ded50b3a\" data-name=\"Layer 1\" width=\"16\" height=\"16\" viewBox=\"0 0 16 16\"><polygon points=\"8.39 7.64 8.39 0 7.61 0 7.61 7.64 0 7.64 0 8.4 7.61 8.4 7.61 16 8.39 16 8.39 8.4 16 8.4 16 7.64 8.39 7.64\"><\/polygon><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"adf49d60-5815-4ece-8d49-00a021de5c06\" data-name=\"Layer 1\" width=\"16\" height=\"16\" viewBox=\"0 0 16 16\"><rect width=\"16\" height=\"16\" style=\"opacity:0\"><\/rect><rect y=\"7.64\" width=\"16\" height=\"0.76\"><\/rect><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Darf ich im Camlica Tower rauchen?<\/a>\n\t\t\t\t\t<\/h4>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1789\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"9\" role=\"region\" aria-labelledby=\"elementor-tab-title-1789\"><p><span style=\"font-weight: 400;\">Nein, im Camlica Tower gilt aus Sicherheitsgr\u00fcnden und um eine angenehme Atmosph\u00e4re f\u00fcr alle Besucher zu gew\u00e4hrleisten, ein striktes Rauchverbot.<\/span><\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h4 id=\"elementor-tab-title-17810\" class=\"elementor-tab-title\" data-tab=\"10\" role=\"button\" aria-controls=\"elementor-tab-content-17810\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"b159ff04-3740-4ac3-96cc-b414ded50b3a\" data-name=\"Layer 1\" width=\"16\" height=\"16\" viewBox=\"0 0 16 16\"><polygon points=\"8.39 7.64 8.39 0 7.61 0 7.61 7.64 0 7.64 0 8.4 7.61 8.4 7.61 16 8.39 16 8.39 8.4 16 8.4 16 7.64 8.39 7.64\"><\/polygon><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"adf49d60-5815-4ece-8d49-00a021de5c06\" data-name=\"Layer 1\" width=\"16\" height=\"16\" viewBox=\"0 0 16 16\"><rect width=\"16\" height=\"16\" style=\"opacity:0\"><\/rect><rect y=\"7.64\" width=\"16\" height=\"0.76\"><\/rect><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Wie lange ist mein Camlica Tower-Ticket g\u00fcltig?<\/a>\n\t\t\t\t\t<\/h4>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-17810\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"10\" role=\"region\" aria-labelledby=\"elementor-tab-title-17810\"><p><span style=\"font-weight: 400;\">Ihr Ticket ist nur f\u00fcr das Kaufdatum g\u00fcltig. Bitte stellen Sie sicher, dass Sie es am zugewiesenen Tag nutzen.<\/span><\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h4 id=\"elementor-tab-title-17811\" class=\"elementor-tab-title\" data-tab=\"11\" role=\"button\" aria-controls=\"elementor-tab-content-17811\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"b159ff04-3740-4ac3-96cc-b414ded50b3a\" data-name=\"Layer 1\" width=\"16\" height=\"16\" viewBox=\"0 0 16 16\"><polygon points=\"8.39 7.64 8.39 0 7.61 0 7.61 7.64 0 7.64 0 8.4 7.61 8.4 7.61 16 8.39 16 8.39 8.4 16 8.4 16 7.64 8.39 7.64\"><\/polygon><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"adf49d60-5815-4ece-8d49-00a021de5c06\" data-name=\"Layer 1\" width=\"16\" height=\"16\" viewBox=\"0 0 16 16\"><rect width=\"16\" height=\"16\" style=\"opacity:0\"><\/rect><rect y=\"7.64\" width=\"16\" height=\"0.76\"><\/rect><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Ist es notwendig, die auf meinem Ticket angegebenen Einlasszeiten strikt einzuhalten?<\/a>\n\t\t\t\t\t<\/h4>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-17811\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"11\" role=\"region\" aria-labelledby=\"elementor-tab-title-17811\"><p><span style=\"font-weight: 400;\">Wir bitten Besucher, sich an die auf den Tickets angegebenen Einlasszeiten zu halten, um eine \u00dcberf\u00fcllung und m\u00f6gliche Unannehmlichkeiten aufgrund von Gesundheits- und Sicherheitsma\u00dfnahmen zu vermeiden.<\/span><\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<script type=\"application\/ld+json\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"FAQPage\",\"mainEntity\":[{\"@type\":\"Question\",\"name\":\"Was kostet der Eintritt zum Camlica-Turm?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p><span style=\\\"font-weight: 400;\\\">Finden Sie es heraus: <a href=\\\"http:\\\/\\\/camlicatower.com\\\/prices-times\\\/\\\">Bitte \\u00fcberpr\\u00fcfen<\\\/a><\\\/span><\\\/p>\\n\"}},{\"@type\":\"Question\",\"name\":\"Ist es m\\u00f6glich, Tickets f\\u00fcr den Camlica Tower Istanbul online zu kaufen?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p><span style=\\\"font-weight: 400;\\\">Absolut, das k\\u00f6nnen Sie! Wir empfehlen Ihnen, Ihre Tickets online zu kaufen, um Ihren Besuch zu optimieren.&nbsp;<\\\/span><\\\/p>\\n<p><a href=\\\"http:\\\/\\\/camlicatower.com\\\/prices-times\\\/\\\" target=\\\"_blank\\\">Bitte \\u00fcberpr\\u00fcfen<\\\/a><\\\/p>\\n\"}},{\"@type\":\"Question\",\"name\":\"Wann ist der Camlica-Turm f\\u00fcr die \\u00d6ffentlichkeit zug\\u00e4nglich?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p><span style=\\\"font-weight: 400;\\\">Besucher k\\u00f6nnen den Camlica-Turm bereits von 10:00 bis 22:00 Uhr erkunden.<\\\/span><\\\/p>\\n\"}},{\"@type\":\"Question\",\"name\":\"Wie buche ich einen Besuch im Camlica-Turm?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p><span style=\\\"font-weight: 400;\\\">Sichern Sie sich jetzt Ihren Platz: <a href=\\\"http:\\\/\\\/camlicatower.com\\\/prices-times\\\/\\\">Bitte ankreuzen<\\\/a><\\\/span><\\\/p>\\n\"}},{\"@type\":\"Question\",\"name\":\"Welche M\\u00f6glichkeiten habe ich, den Camlica-Turm zu erreichen?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p><span style=\\\"font-weight: 400;\\\">Der Camlica-Turm ist bequem mit \\u00f6ffentlichen Verkehrsmitteln und Taxis zu erreichen und kann von der europ\\u00e4ischen Seite aus mit einem einfachen Taxi erreicht werden, das etwa 40 Euro kostet. Pendler mit \\u00f6ffentlichen Verkehrsmitteln k\\u00f6nnen die Marmaray-Linie zum Bahnhof \\u00dcsk\\u00fcdar nehmen und anschlie\\u00dfend den Bus Nr. 15 von \\u00dcsk\\u00fcdar nach Camlica nehmen. Dar\\u00fcber hinaus k\\u00f6nnen Sie mit Taxis direkt zum Turm fahren. Wenn Sie mit dem Auto anreisen, stehen Ihnen am Camlica Tower Parkpl\\u00e4tze zur Verf\\u00fcgung.<\\\/span><\\\/p>\\n\"}},{\"@type\":\"Question\",\"name\":\"Wie zug\\u00e4nglich ist der Camlica-Turm?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p><span style=\\\"font-weight: 400;\\\">Wir sind stolz darauf, verk\\u00fcnden zu k\\u00f6nnen, dass der Camlica Tower vollst\\u00e4ndig f\\u00fcr den Empfang von Rollstuhlfahrern ausgestattet ist. Wir sind bestrebt, die beeindruckenden Aussichten und Einrichtungen, die der Turm bietet, allen Besuchern zug\\u00e4nglich zu machen.<\\\/span><\\\/p>\\n\"}},{\"@type\":\"Question\",\"name\":\"Was muss ich nach dem Kauf meines Tickets tun?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p><span style=\\\"font-weight: 400;\\\">Sobald Sie Ihr Ticket in der Hand haben, k\\u00f6nnen Sie unsere weitl\\u00e4ufigen G\\u00e4rten genie\\u00dfen oder die Inneneinrichtungen im Turm wie unsere Cafeteria und verschiedene Aktivit\\u00e4tsbereiche erkunden.<\\\/span><\\\/p>\\n\"}},{\"@type\":\"Question\",\"name\":\"Wie lange kann ich auf der Aussichtsplattform am Turm bleiben?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p><span style=\\\"font-weight: 400;\\\">Damit alle unsere Besucher die Aussicht ausreichend genie\\u00dfen k\\u00f6nnen, erlauben wir auf unseren Aussichtsplattformen eine Besuchsdauer von bis zu eineinhalb Stunden.<\\\/span><\\\/p>\\n\"}},{\"@type\":\"Question\",\"name\":\"Darf ich im Camlica Tower rauchen?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p><span style=\\\"font-weight: 400;\\\">Nein, im Camlica Tower gilt aus Sicherheitsgr\\u00fcnden und um eine angenehme Atmosph\\u00e4re f\\u00fcr alle Besucher zu gew\\u00e4hrleisten, ein striktes Rauchverbot.<\\\/span><\\\/p>\\n\"}},{\"@type\":\"Question\",\"name\":\"Wie lange ist mein Camlica Tower-Ticket g\\u00fcltig?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p><span style=\\\"font-weight: 400;\\\">Ihr Ticket ist nur f\\u00fcr das Kaufdatum g\\u00fcltig. Bitte stellen Sie sicher, dass Sie es am zugewiesenen Tag nutzen.<\\\/span><\\\/p>\\n\"}},{\"@type\":\"Question\",\"name\":\"Ist es notwendig, die auf meinem Ticket angegebenen Einlasszeiten strikt einzuhalten?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p><span style=\\\"font-weight: 400;\\\">Wir bitten Besucher, sich an die auf den Tickets angegebenen Einlasszeiten zu halten, um eine \\u00dcberf\\u00fcllung und m\\u00f6gliche Unannehmlichkeiten aufgrund von Gesundheits- und Sicherheitsma\\u00dfnahmen zu vermeiden.<\\\/span><\\\/p>\\n\"}}]}<\/script>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5b0631fb elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-widget elementor-widget-toggle\" data-id=\"5b0631fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h4 id=\"elementor-tab-title-1521\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1521\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"b159ff04-3740-4ac3-96cc-b414ded50b3a\" data-name=\"Layer 1\" width=\"16\" height=\"16\" viewBox=\"0 0 16 16\"><polygon points=\"8.39 7.64 8.39 0 7.61 0 7.61 7.64 0 7.64 0 8.4 7.61 8.4 7.61 16 8.39 16 8.39 8.4 16 8.4 16 7.64 8.39 7.64\"><\/polygon><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"adf49d60-5815-4ece-8d49-00a021de5c06\" data-name=\"Layer 1\" width=\"16\" height=\"16\" viewBox=\"0 0 16 16\"><rect width=\"16\" height=\"16\" style=\"opacity:0\"><\/rect><rect y=\"7.64\" width=\"16\" height=\"0.76\"><\/rect><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Wie hoch ist der Camlica Tower Istanbul?<\/a>\n\t\t\t\t\t<\/h4>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1521\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1521\"><p><span style=\"font-weight: 400;\">Das beeindruckende Bauwerk des Camlica-Turms erreicht eine bemerkenswerte H\u00f6he von 369 Metern und ist damit eines der h\u00f6chsten und markantesten Wahrzeichen Istanbuls, das einen atemberaubenden Panoramablick auf das beeindruckende Stadtbild Istanbuls bietet.<\/span><\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h4 id=\"elementor-tab-title-1522\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-1522\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"b159ff04-3740-4ac3-96cc-b414ded50b3a\" data-name=\"Layer 1\" width=\"16\" height=\"16\" viewBox=\"0 0 16 16\"><polygon points=\"8.39 7.64 8.39 0 7.61 0 7.61 7.64 0 7.64 0 8.4 7.61 8.4 7.61 16 8.39 16 8.39 8.4 16 8.4 16 7.64 8.39 7.64\"><\/polygon><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"adf49d60-5815-4ece-8d49-00a021de5c06\" data-name=\"Layer 1\" width=\"16\" height=\"16\" viewBox=\"0 0 16 16\"><rect width=\"16\" height=\"16\" style=\"opacity:0\"><\/rect><rect y=\"7.64\" width=\"16\" height=\"0.76\"><\/rect><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Welche gastronomischen Einrichtungen gibt es im Camlica Tower Istanbul?<\/a>\n\t\t\t\t\t<\/h4>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1522\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-1522\"><p><span style=\"font-weight: 400;\">Der Camlica Tower beherbergt eine Vielzahl von gastronomischen Einrichtungen, die unterschiedliche Gaumen bedienen. Freuen Sie sich auf entz\u00fcckende Restaurants und Caf\u00e9s, die alle ein umfangreiches Speiseangebot und einen beeindruckenden Blick auf die Stadt bieten. Von leichten H\u00e4ppchen \u00fcber gem\u00fctliche Mittagessen bis hin zu gehobener K\u00fcche ist f\u00fcr jedes kulinarische Verlangen etwas dabei.<\/span><\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h4 id=\"elementor-tab-title-1523\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-1523\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"b159ff04-3740-4ac3-96cc-b414ded50b3a\" data-name=\"Layer 1\" width=\"16\" height=\"16\" viewBox=\"0 0 16 16\"><polygon points=\"8.39 7.64 8.39 0 7.61 0 7.61 7.64 0 7.64 0 8.4 7.61 8.4 7.61 16 8.39 16 8.39 8.4 16 8.4 16 7.64 8.39 7.64\"><\/polygon><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"adf49d60-5815-4ece-8d49-00a021de5c06\" data-name=\"Layer 1\" width=\"16\" height=\"16\" viewBox=\"0 0 16 16\"><rect width=\"16\" height=\"16\" style=\"opacity:0\"><\/rect><rect y=\"7.64\" width=\"16\" height=\"0.76\"><\/rect><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Warum sollte ich den Camlica Tower Istanbul besuchen?<\/a>\n\t\t\t\t\t<\/h4>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1523\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-1523\"><p><span style=\"font-weight: 400;\">Der Camlica-Turm bietet einen unvergleichlichen Panoramablick auf Istanbul und ist ein unverzichtbares Ziel f\u00fcr jeden Istanbul-Besucher. Neben der einzigartigen Aussicht auf die Stadt aus der Vogelperspektive beherbergt der Turm verschiedene Annehmlichkeiten wie Restaurants, Caf\u00e9s und Ausstellungen und verspricht ein bereicherndes und unvergessliches Erlebnis.<\/span><\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h4 id=\"elementor-tab-title-1524\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-1524\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"b159ff04-3740-4ac3-96cc-b414ded50b3a\" data-name=\"Layer 1\" width=\"16\" height=\"16\" viewBox=\"0 0 16 16\"><polygon points=\"8.39 7.64 8.39 0 7.61 0 7.61 7.64 0 7.64 0 8.4 7.61 8.4 7.61 16 8.39 16 8.39 8.4 16 8.4 16 7.64 8.39 7.64\"><\/polygon><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"adf49d60-5815-4ece-8d49-00a021de5c06\" data-name=\"Layer 1\" width=\"16\" height=\"16\" viewBox=\"0 0 16 16\"><rect width=\"16\" height=\"16\" style=\"opacity:0\"><\/rect><rect y=\"7.64\" width=\"16\" height=\"0.76\"><\/rect><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Ist es sicher, den Camlica Tower Istanbul zu besuchen?<\/a>\n\t\t\t\t\t<\/h4>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1524\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-1524\"><p><span style=\"font-weight: 400;\">Sicherlich! Die Gew\u00e4hrleistung der Sicherheit unserer Besucher ist unser gr\u00f6\u00dftes Anliegen. Wir verf\u00fcgen \u00fcber umfassende Sicherheitsprotokolle und -ma\u00dfnahmen, um einen sicheren Besuch im Camlica Tower zu gew\u00e4hrleisten. Wir empfehlen jedoch allen Besuchern, w\u00e4hrend ihres Besuchs wachsam zu bleiben und alle Sicherheitsrichtlinien einzuhalten.<\/span><\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h4 id=\"elementor-tab-title-1525\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-1525\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"b159ff04-3740-4ac3-96cc-b414ded50b3a\" data-name=\"Layer 1\" width=\"16\" height=\"16\" viewBox=\"0 0 16 16\"><polygon points=\"8.39 7.64 8.39 0 7.61 0 7.61 7.64 0 7.64 0 8.4 7.61 8.4 7.61 16 8.39 16 8.39 8.4 16 8.4 16 7.64 8.39 7.64\"><\/polygon><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"adf49d60-5815-4ece-8d49-00a021de5c06\" data-name=\"Layer 1\" width=\"16\" height=\"16\" viewBox=\"0 0 16 16\"><rect width=\"16\" height=\"16\" style=\"opacity:0\"><\/rect><rect y=\"7.64\" width=\"16\" height=\"0.76\"><\/rect><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Wann ist die beste Zeit, den Camlica Tower Istanbul zu besuchen?<\/a>\n\t\t\t\t\t<\/h4>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1525\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-1525\"><p><span style=\"font-weight: 400;\">Um dem Trubel zu entgehen und entweder einen bezaubernden Sonnenaufgang oder Sonnenuntergang von der Aussichtsplattform des Turms aus zu genie\u00dfen, empfehlen wir Ihnen, den Camlica Tower Istanbul am fr\u00fchen Morgen oder am sp\u00e4ten Nachmittag zu besuchen.<\/span><\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h4 id=\"elementor-tab-title-1526\" class=\"elementor-tab-title\" data-tab=\"6\" role=\"button\" aria-controls=\"elementor-tab-content-1526\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"b159ff04-3740-4ac3-96cc-b414ded50b3a\" data-name=\"Layer 1\" width=\"16\" height=\"16\" viewBox=\"0 0 16 16\"><polygon points=\"8.39 7.64 8.39 0 7.61 0 7.61 7.64 0 7.64 0 8.4 7.61 8.4 7.61 16 8.39 16 8.39 8.4 16 8.4 16 7.64 8.39 7.64\"><\/polygon><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"adf49d60-5815-4ece-8d49-00a021de5c06\" data-name=\"Layer 1\" width=\"16\" height=\"16\" viewBox=\"0 0 16 16\"><rect width=\"16\" height=\"16\" style=\"opacity:0\"><\/rect><rect y=\"7.64\" width=\"16\" height=\"0.76\"><\/rect><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Kann ich im Camlica Tower Istanbul Fotos machen?<\/a>\n\t\t\t\t\t<\/h4>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1526\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"6\" role=\"region\" aria-labelledby=\"elementor-tab-title-1526\"><p><span style=\"font-weight: 400;\">Kann ich im Camlica Tower Istanbul Fotos machen? Wir ermutigen Besucher, die atemberaubende Aussicht vom Camlica-Turm einzufangen, einem beliebten Ort, der f\u00fcr seine unvergleichliche Aussicht auf die Skyline von Istanbul bekannt ist.<\/span><\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h4 id=\"elementor-tab-title-1527\" class=\"elementor-tab-title\" data-tab=\"7\" role=\"button\" aria-controls=\"elementor-tab-content-1527\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"b159ff04-3740-4ac3-96cc-b414ded50b3a\" data-name=\"Layer 1\" width=\"16\" height=\"16\" viewBox=\"0 0 16 16\"><polygon points=\"8.39 7.64 8.39 0 7.61 0 7.61 7.64 0 7.64 0 8.4 7.61 8.4 7.61 16 8.39 16 8.39 8.4 16 8.4 16 7.64 8.39 7.64\"><\/polygon><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"adf49d60-5815-4ece-8d49-00a021de5c06\" data-name=\"Layer 1\" width=\"16\" height=\"16\" viewBox=\"0 0 16 16\"><rect width=\"16\" height=\"16\" style=\"opacity:0\"><\/rect><rect y=\"7.64\" width=\"16\" height=\"0.76\"><\/rect><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Gibt es Parkpl\u00e4tze f\u00fcr Fahrzeuge?<\/a>\n\t\t\t\t\t<\/h4>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1527\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"7\" role=\"region\" aria-labelledby=\"elementor-tab-title-1527\"><p><span style=\"font-weight: 400;\">Ja, f\u00fcr diejenigen, die mit dem Auto anreisen, stehen in der N\u00e4he des Turms ausgewiesene Parkpl\u00e4tze zur Verf\u00fcgung.<\/span><\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h4 id=\"elementor-tab-title-1528\" class=\"elementor-tab-title\" data-tab=\"8\" role=\"button\" aria-controls=\"elementor-tab-content-1528\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"b159ff04-3740-4ac3-96cc-b414ded50b3a\" data-name=\"Layer 1\" width=\"16\" height=\"16\" viewBox=\"0 0 16 16\"><polygon points=\"8.39 7.64 8.39 0 7.61 0 7.61 7.64 0 7.64 0 8.4 7.61 8.4 7.61 16 8.39 16 8.39 8.4 16 8.4 16 7.64 8.39 7.64\"><\/polygon><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"adf49d60-5815-4ece-8d49-00a021de5c06\" data-name=\"Layer 1\" width=\"16\" height=\"16\" viewBox=\"0 0 16 16\"><rect width=\"16\" height=\"16\" style=\"opacity:0\"><\/rect><rect y=\"7.64\" width=\"16\" height=\"0.76\"><\/rect><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Welche Gegenst\u00e4nde sind im Camlica-Turm verboten?<\/a>\n\t\t\t\t\t<\/h4>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1528\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"8\" role=\"region\" aria-labelledby=\"elementor-tab-title-1528\"><p><span style=\"font-weight: 400;\">Zur Sicherheit aller sind im Camlica Tower Gep\u00e4ck, Rucks\u00e4cke, Flaschen mit fl\u00fcssigem Inhalt und Metallgegenst\u00e4nde verboten. Nach der Sicherheitskontrolle k\u00f6nnen Ihre pers\u00f6nlichen Gegenst\u00e4nde sicher in der Garderobe aufbewahrt werden.<\/span><\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h4 id=\"elementor-tab-title-1529\" class=\"elementor-tab-title\" data-tab=\"9\" role=\"button\" aria-controls=\"elementor-tab-content-1529\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"b159ff04-3740-4ac3-96cc-b414ded50b3a\" data-name=\"Layer 1\" width=\"16\" height=\"16\" viewBox=\"0 0 16 16\"><polygon points=\"8.39 7.64 8.39 0 7.61 0 7.61 7.64 0 7.64 0 8.4 7.61 8.4 7.61 16 8.39 16 8.39 8.4 16 8.4 16 7.64 8.39 7.64\"><\/polygon><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"adf49d60-5815-4ece-8d49-00a021de5c06\" data-name=\"Layer 1\" width=\"16\" height=\"16\" viewBox=\"0 0 16 16\"><rect width=\"16\" height=\"16\" style=\"opacity:0\"><\/rect><rect y=\"7.64\" width=\"16\" height=\"0.76\"><\/rect><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Kann ich mein Haustier in den Camlica Tower mitnehmen?<\/a>\n\t\t\t\t\t<\/h4>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1529\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"9\" role=\"region\" aria-labelledby=\"elementor-tab-title-1529\"><p><span style=\"font-weight: 400;\">Aus Gr\u00fcnden des Komforts und der Sicherheit aller Besucher sind Haustiere im Camlica Tower nicht gestattet. Wir empfehlen Ihnen, vor Ihrem Besuch entsprechende Vorkehrungen f\u00fcr Ihre Haustiere zu treffen.<\/span><\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h4 id=\"elementor-tab-title-15210\" class=\"elementor-tab-title\" data-tab=\"10\" role=\"button\" aria-controls=\"elementor-tab-content-15210\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"b159ff04-3740-4ac3-96cc-b414ded50b3a\" data-name=\"Layer 1\" width=\"16\" height=\"16\" viewBox=\"0 0 16 16\"><polygon points=\"8.39 7.64 8.39 0 7.61 0 7.61 7.64 0 7.64 0 8.4 7.61 8.4 7.61 16 8.39 16 8.39 8.4 16 8.4 16 7.64 8.39 7.64\"><\/polygon><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"adf49d60-5815-4ece-8d49-00a021de5c06\" data-name=\"Layer 1\" width=\"16\" height=\"16\" viewBox=\"0 0 16 16\"><rect width=\"16\" height=\"16\" style=\"opacity:0\"><\/rect><rect y=\"7.64\" width=\"16\" height=\"0.76\"><\/rect><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Was erwartet mich im Inneren des Camlica-Turms?<\/a>\n\t\t\t\t\t<\/h4>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-15210\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"10\" role=\"region\" aria-labelledby=\"elementor-tab-title-15210\"><p><span style=\"font-weight: 400;\">Der Camlica-Turm, auch bekannt als Fernsehfunkturm K\u00fc\u00e7\u00fck \u00c7aml\u0131ca (t\u00fcrkisch: K\u00fc\u00e7\u00fck \u00c7aml\u0131ca TV-Radyo Kulesi), ist ein Mehrzweckziel. Er ist nicht nur ein Fernseh- und Radiosendeturm, sondern bietet auch eine Vielzahl anderer<\/span><\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h4 id=\"elementor-tab-title-15211\" class=\"elementor-tab-title\" data-tab=\"11\" role=\"button\" aria-controls=\"elementor-tab-content-15211\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"b159ff04-3740-4ac3-96cc-b414ded50b3a\" data-name=\"Layer 1\" width=\"16\" height=\"16\" viewBox=\"0 0 16 16\"><polygon points=\"8.39 7.64 8.39 0 7.61 0 7.61 7.64 0 7.64 0 8.4 7.61 8.4 7.61 16 8.39 16 8.39 8.4 16 8.4 16 7.64 8.39 7.64\"><\/polygon><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"adf49d60-5815-4ece-8d49-00a021de5c06\" data-name=\"Layer 1\" width=\"16\" height=\"16\" viewBox=\"0 0 16 16\"><rect width=\"16\" height=\"16\" style=\"opacity:0\"><\/rect><rect y=\"7.64\" width=\"16\" height=\"0.76\"><\/rect><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Wie funktioniert das Warteschlangenprotokoll f\u00fcr G\u00e4ste mit Reservierung?<\/a>\n\t\t\t\t\t<\/h4>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-15211\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"11\" role=\"region\" aria-labelledby=\"elementor-tab-title-15211\"><p><span style=\"font-weight: 400;\">Bitte beachten Sie, dass es aufgrund zus\u00e4tzlicher Hygienema\u00dfnahmen oder der Koordination der Abreise fr\u00fcherer Besucher zu geringf\u00fcgigen Verz\u00f6gerungen kommen kann. Bitte beachten Sie, dass es aufgrund zus\u00e4tzlicher Hygienema\u00dfnahmen oder der Koordination der Abreise fr\u00fcherer Besucher zu geringf\u00fcgigen Verz\u00f6gerungen kommen kann.<\/span><\/p>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<script type=\"application\/ld+json\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"FAQPage\",\"mainEntity\":[{\"@type\":\"Question\",\"name\":\"Wie hoch ist der Camlica Tower Istanbul?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p><span style=\\\"font-weight: 400;\\\">Das beeindruckende Bauwerk des Camlica-Turms erreicht eine bemerkenswerte H\\u00f6he von 369 Metern und ist damit eines der h\\u00f6chsten und markantesten Wahrzeichen Istanbuls, das einen atemberaubenden Panoramablick auf das beeindruckende Stadtbild Istanbuls bietet.<\\\/span><\\\/p>\\n\"}},{\"@type\":\"Question\",\"name\":\"Welche gastronomischen Einrichtungen gibt es im Camlica Tower Istanbul?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p><span style=\\\"font-weight: 400;\\\">Der Camlica Tower beherbergt eine Vielzahl von gastronomischen Einrichtungen, die unterschiedliche Gaumen bedienen. Freuen Sie sich auf entz\\u00fcckende Restaurants und Caf\\u00e9s, die alle ein umfangreiches Speiseangebot und einen beeindruckenden Blick auf die Stadt bieten. Von leichten H\\u00e4ppchen \\u00fcber gem\\u00fctliche Mittagessen bis hin zu gehobener K\\u00fcche ist f\\u00fcr jedes kulinarische Verlangen etwas dabei.<\\\/span><\\\/p>\\n\"}},{\"@type\":\"Question\",\"name\":\"Warum sollte ich den Camlica Tower Istanbul besuchen?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p><span style=\\\"font-weight: 400;\\\">Der Camlica-Turm bietet einen unvergleichlichen Panoramablick auf Istanbul und ist ein unverzichtbares Ziel f\\u00fcr jeden Istanbul-Besucher. Neben der einzigartigen Aussicht auf die Stadt aus der Vogelperspektive beherbergt der Turm verschiedene Annehmlichkeiten wie Restaurants, Caf\\u00e9s und Ausstellungen und verspricht ein bereicherndes und unvergessliches Erlebnis.<\\\/span><\\\/p>\\n\"}},{\"@type\":\"Question\",\"name\":\"Ist es sicher, den Camlica Tower Istanbul zu besuchen?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p><span style=\\\"font-weight: 400;\\\">Sicherlich! Die Gew\\u00e4hrleistung der Sicherheit unserer Besucher ist unser gr\\u00f6\\u00dftes Anliegen. Wir verf\\u00fcgen \\u00fcber umfassende Sicherheitsprotokolle und -ma\\u00dfnahmen, um einen sicheren Besuch im Camlica Tower zu gew\\u00e4hrleisten. Wir empfehlen jedoch allen Besuchern, w\\u00e4hrend ihres Besuchs wachsam zu bleiben und alle Sicherheitsrichtlinien einzuhalten.<\\\/span><\\\/p>\\n\"}},{\"@type\":\"Question\",\"name\":\"Wann ist die beste Zeit, den Camlica Tower Istanbul zu besuchen?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p><span style=\\\"font-weight: 400;\\\">Um dem Trubel zu entgehen und entweder einen bezaubernden Sonnenaufgang oder Sonnenuntergang von der Aussichtsplattform des Turms aus zu genie\\u00dfen, empfehlen wir Ihnen, den Camlica Tower Istanbul am fr\\u00fchen Morgen oder am sp\\u00e4ten Nachmittag zu besuchen.<\\\/span><\\\/p>\\n\"}},{\"@type\":\"Question\",\"name\":\"Kann ich im Camlica Tower Istanbul Fotos machen?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p><span style=\\\"font-weight: 400;\\\">Kann ich im Camlica Tower Istanbul Fotos machen? Wir ermutigen Besucher, die atemberaubende Aussicht vom Camlica-Turm einzufangen, einem beliebten Ort, der f\\u00fcr seine unvergleichliche Aussicht auf die Skyline von Istanbul bekannt ist.<\\\/span><\\\/p>\\n\"}},{\"@type\":\"Question\",\"name\":\"Gibt es Parkpl\\u00e4tze f\\u00fcr Fahrzeuge?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p><span style=\\\"font-weight: 400;\\\">Ja, f\\u00fcr diejenigen, die mit dem Auto anreisen, stehen in der N\\u00e4he des Turms ausgewiesene Parkpl\\u00e4tze zur Verf\\u00fcgung.<\\\/span><\\\/p>\\n\"}},{\"@type\":\"Question\",\"name\":\"Welche Gegenst\\u00e4nde sind im Camlica-Turm verboten?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p><span style=\\\"font-weight: 400;\\\">Zur Sicherheit aller sind im Camlica Tower Gep\\u00e4ck, Rucks\\u00e4cke, Flaschen mit fl\\u00fcssigem Inhalt und Metallgegenst\\u00e4nde verboten. Nach der Sicherheitskontrolle k\\u00f6nnen Ihre pers\\u00f6nlichen Gegenst\\u00e4nde sicher in der Garderobe aufbewahrt werden.<\\\/span><\\\/p>\\n\"}},{\"@type\":\"Question\",\"name\":\"Kann ich mein Haustier in den Camlica Tower mitnehmen?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p><span style=\\\"font-weight: 400;\\\">Aus Gr\\u00fcnden des Komforts und der Sicherheit aller Besucher sind Haustiere im Camlica Tower nicht gestattet. Wir empfehlen Ihnen, vor Ihrem Besuch entsprechende Vorkehrungen f\\u00fcr Ihre Haustiere zu treffen.<\\\/span><\\\/p>\\n\"}},{\"@type\":\"Question\",\"name\":\"Was erwartet mich im Inneren des Camlica-Turms?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p><span style=\\\"font-weight: 400;\\\">Der Camlica-Turm, auch bekannt als Fernsehfunkturm K\\u00fc\\u00e7\\u00fck \\u00c7aml\\u0131ca (t\\u00fcrkisch: K\\u00fc\\u00e7\\u00fck \\u00c7aml\\u0131ca TV-Radyo Kulesi), ist ein Mehrzweckziel. Er ist nicht nur ein Fernseh- und Radiosendeturm, sondern bietet auch eine Vielzahl anderer<\\\/span><\\\/p>\\n\"}},{\"@type\":\"Question\",\"name\":\"Wie funktioniert das Warteschlangenprotokoll f\\u00fcr G\\u00e4ste mit Reservierung?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p><span style=\\\"font-weight: 400;\\\">Bitte beachten Sie, dass es aufgrund zus\\u00e4tzlicher Hygienema\\u00dfnahmen oder der Koordination der Abreise fr\\u00fcherer Besucher zu geringf\\u00fcgigen Verz\\u00f6gerungen kommen kann. Bitte beachten Sie, dass es aufgrund zus\\u00e4tzlicher Hygienema\\u00dfnahmen oder der Koordination der Abreise fr\\u00fcherer Besucher zu geringf\\u00fcgigen Verz\\u00f6gerungen kommen kann.<\\\/span><\\\/p>\\n\"}}]}<\/script>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>http:\/\/camlicatower.com\/wp-content\/uploads\/2023\/08\/Camlica-Tower_1.mp4http:\/\/camlicatower.com\/wp-content\/uploads\/2023\/08\/Camlica-Tower_1.mp4 DIE CAMLICA TURM Atemberaubende Ausblicke, unvergessliche Erlebnisse! BUCHEN SIE JETZT \u00d6ffnungszeiten 10:00 \u2013 22:00<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-16646","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/camlicatower.com\/de\/wp-json\/wp\/v2\/pages\/16646","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/camlicatower.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/camlicatower.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/camlicatower.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/camlicatower.com\/de\/wp-json\/wp\/v2\/comments?post=16646"}],"version-history":[{"count":8,"href":"https:\/\/camlicatower.com\/de\/wp-json\/wp\/v2\/pages\/16646\/revisions"}],"predecessor-version":[{"id":17288,"href":"https:\/\/camlicatower.com\/de\/wp-json\/wp\/v2\/pages\/16646\/revisions\/17288"}],"wp:attachment":[{"href":"https:\/\/camlicatower.com\/de\/wp-json\/wp\/v2\/media?parent=16646"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}